{"id":9126,"date":"2023-01-21T12:38:58","date_gmt":"2023-01-21T15:38:58","guid":{"rendered":"https:\/\/g1.globo.com\/pb\/paraiba\/noticia\/2023\/01\/21\/apagao-em-maternidade-forcou-bebes-a-serem-transferidos-de-uti-em-campina-grande.ghtml"},"modified":"2023-01-21T12:38:58","modified_gmt":"2023-01-21T15:38:58","slug":"apagao-em-maternidade-forcou-bebes-a-serem-transferidos-de-uti-em-campina-grande","status":"publish","type":"post","link":"https:\/\/sindaopcpb.org.br\/index.php\/2023\/01\/21\/apagao-em-maternidade-forcou-bebes-a-serem-transferidos-de-uti-em-campina-grande\/","title":{"rendered":"Apag\u00e3o em maternidade for\u00e7ou beb\u00eas a serem transferidos de UTI em Campina Grande"},"content":{"rendered":"   <img src=\"https:\/\/s2.glbimg.com\/PqEy9zRwVfQDggl_4t-VPHUqRJI=\/s.glbimg.com\/jo\/g1\/f\/original\/2014\/04\/12\/isea-cg-frente.jpg\" \/><br \/>   Pr\u00e9dio onde funciona o Isea ficou sem energia el\u00e9trica e gerador n\u00e3o funcionou. Instituto de Sa\u00fade Elp\u00eddio de Almeida (ISEA), em Campina Grande\nReprodu\u00e7\u00e3o\/TV Para\u00edba\nA maternidade do Instituto de Sa\u00fade Elp\u00eddio de Almeida (Isea), em Campina Grande, ficou sem energia el\u00e9trica e os beb\u00eas da UTI precisaram ser transferidos no final da manh\u00e3 deste s\u00e1bado (21).\nO apag\u00e3o aconteceu apenas no pr\u00e9dio principal da maternidade. Al\u00e9m da falta de energia, o gerador do Instituto tamb\u00e9m n\u00e3o funcionou.\nOs pr\u00e9dios anexos ao Isea e outros pr\u00e9dios do Centro n\u00e3o foram atingidos. O Instituto informou que o problema teria sido na instala\u00e7\u00e3o el\u00e9trica do pr\u00e9dio.\nAt\u00e9 o momento, sete beb\u00eas foram transferidos pelo Samu para outras unidades. Nenhuma m\u00e3e foi transferida, pois os equipamentos s\u00e3o mantidos por bateria e funcionam normalmente.\nDe acordo com a dire\u00e7\u00e3o do hospital, a situa\u00e7\u00e3o est\u00e1 sob controle e os beb\u00eas foram transferidos de maneira preventiva para outros dois hospitais no Centro de Campina Grande.\nA secretaria de Sa\u00fade de Campina Grande disse em nota que o incidente n\u00e3o causou dano a nenhum rec\u00e9m-nascido, gestante ou pu\u00e9rpera. \"A equipe de engenharia da Secretaria Municipal de Sa\u00fade trabalha para identificar o que pode ter causado o problema, visto que a unidade disp\u00f5e de geradores de energia el\u00e9trica\", informou.\nO prefeito Bruno Cunha Lima e o secret\u00e1rio de Sa\u00fade Gilney Porto est\u00e3o na maternidade para acomapanhar a situa\u00e7\u00e3o at\u00e9 o restabelecimento do fornecimento da energia, ainda de acordo com a Secretaria de Sa\u00fade.\nV\u00eddeos mais assistidos do g1 Para\u00edba ","protected":false},"excerpt":{"rendered":"<p>      Pr\u00e9dio onde funciona o Isea ficou sem energia el\u00e9trica e gerador n\u00e3o funcionou. Instituto de Sa\u00fade Elp\u00eddio de Almeida (ISEA), em Campina Grande<br \/>\nReprodu\u00e7\u00e3o\/TV Para\u00edba<br \/>\nA maternidade do Instituto de Sa\u00fade Elp\u00eddio de Almeida (Isea), em Campina Grande&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[34],"tags":[35],"class_list":["post-9126","post","type-post","status-publish","format-standard","hentry","category-g1","tag-g1"],"author_meta":{"display_name":"g1 &gt; Para\u00edba","author_link":"https:\/\/sindaopcpb.org.br\/author\/g1-paraiba\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/g1\/\" class=\"advgb-post-tax-term\">G1<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">G1<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/g1\/\" class=\"advgb-post-tax-term\">g1<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">g1<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 4 anos atr\u00e1s","modified":"Atualizado 4 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 21 de janeiro de 2023","modified":"Atualizado em 21 de janeiro de 2023"},"absolute_dates_time":{"created":"Publicado em 21 de janeiro de 2023 12:38","modified":"Atualizado em 21 de janeiro de 2023 12:38"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/9126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=9126"}],"version-history":[{"count":2,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/9126\/revisions"}],"predecessor-version":[{"id":9130,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/9126\/revisions\/9130"}],"wp:attachment":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=9126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=9126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=9126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}