{"id":68475,"date":"2026-07-01T13:09:50","date_gmt":"2026-07-01T16:09:50","guid":{"rendered":"https:\/\/g1.globo.com\/pb\/paraiba\/noticia\/2026\/07\/01\/policiais-presos-em-esquema-de-trafico-de-drogas-planejavam-tornar-delegado-superintendente-da-policia-e-acabar-com-delegacia.ghtml"},"modified":"2026-07-01T13:09:50","modified_gmt":"2026-07-01T16:09:50","slug":"policiais-presos-em-esquema-de-trafico-de-drogas-planejavam-tornar-delegado-superintendente-da-policia-e-acabar-com-delegacia","status":"publish","type":"post","link":"https:\/\/sindaopcpb.org.br\/index.php\/2026\/07\/01\/policiais-presos-em-esquema-de-trafico-de-drogas-planejavam-tornar-delegado-superintendente-da-policia-e-acabar-com-delegacia\/","title":{"rendered":"Policiais presos em esquema de tr\u00e1fico de drogas planejavam tornar delegado superintendente da pol\u00edcia e acabar com delegacia"},"content":{"rendered":"   <img src=\"https:\/\/s2-g1.glbimg.com\/adMP1uO-lLxbklvquGpIKMogxPs=\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2026\/p\/e\/63qkCPTPSQOgFZYXxBBw\/verton.png\" \/><br \/>     Policiais envolvidos com o tr\u00e1fico de drogas planejavam acabar com a Draco\n Um dos \u00e1udios da investiga\u00e7\u00e3o que resultou na pris\u00e3o do delegado Braz Morroni, de dois agentes da Pol\u00edcia Civil e de outros sete investigados mostra um dos agentes presos, o policial civil Everton Aires, conhecido como \u201cBomba\u201d, dizendo que estava tentando \u201cemplacar\u201d o delegado para superintendente da Pol\u00edcia Civil. \nNo trecho ao qual o g1 teve acesso, Bomba chega a falar em \u201cdesmanchar\u201d a Draco, que \u00e9 a Delegacia de Repress\u00e3o ao Crime Organizado. N\u00e3o se sabe para quem o policial preso enviou a mensagem. \n\u201cA gente est\u00e1 vendo se consegue emplacar para ele ser superintendente,  porque, sendo superintendente, a gente consegue ter mais acesso, a gente consegue ter controle de informa\u00e7\u00e3o e consegue desmanchar essa p**** dessa Draco\".\n\u2705 Clique aqui para seguir o canal do g1 PB no WhatsApp\nDe acordo com a investiga\u00e7\u00e3o, Everton Rychelyson da Silva Aires, o \"Bomba\", apontado como principal operador do esquema, recebeu R$ 198.950 em dep\u00f3sitos em esp\u00e9cie, sem identifica\u00e7\u00e3o dos depositantes, entre outubro de 2025 e janeiro de 2026. A movimenta\u00e7\u00e3o chamou a aten\u00e7\u00e3o dos investigadores, que passaram a cruzar os dados financeiros com conversas armazenadas em dispositivos apreendidos. \nOutros \u00e1udios da investiga\u00e7\u00e3o \nEverton foi apontado como sendo um dos principais operadores do esquema criminoso. Ele \u00e9 agente da Pol\u00edcia Civil\nTV Cabo Branco\nA investiga\u00e7\u00e3o que resultou na Opera\u00e7\u00e3o P\u00e9rfidus analisou 40 mil \u00e1udios. Entre esses \u00e1udios, um dos principais \u00e9 de 12 de novembro de 2025, data em que \u201cBomba\u201d recebeu R$ 62 mil em dep\u00f3sitos sem identifica\u00e7\u00e3o do depositante. Nesse mesmo dia, investigadores localizaram conversas entre ele e um suposto traficante identificado como Jos\u00e9 Alexandrino de Lira J\u00fanior.\nNo di\u00e1logo, Everton afirma que a droga teria vindo do estado do Acre e cita a atua\u00e7\u00e3o da fac\u00e7\u00e3o criminosa \"Fam\u00edlia do Norte\" no envio do material. Segundo ele, ao chegar \u00e0 Para\u00edba, a droga teria a embalagem alterada conforme a fac\u00e7\u00e3o respons\u00e1vel pela distribui\u00e7\u00e3o.\n\u201cEssas vieram l\u00e1 do Acre, daquela Fam\u00edlia do Norte. Eles ficavam mandando pra c\u00e1, a\u00ed vinha s\u00f3 com essas embalagens transparentes. O cara da Okaida queira ele enrolava de fita amarela. O cara do Comando Vermelho queria e ele enrolava de fita vermelha\u201d, diz Everton em um dos \u00e1udios.\nLEIA TAMB\u00c9M:\nInvestiga\u00e7\u00e3o que levou \u00e0 pris\u00e3o de delegado na PB come\u00e7ou ap\u00f3s den\u00fancia de traficante, diz pol\u00edcia\nQuem \u00e9 quem em esquema que levou \u00e0 pris\u00e3o de delegado na PB\nEm outros \u00e1udios, Everton relata ter repassado drogas para uma pessoa identificada como \"Dudu\". Na sequ\u00eancia, ele tamb\u00e9m diz que parte da droga teria sido entregue a informantes e que o pagamento teria sido feito com a pr\u00f3pria mercadoria apreendida.\n\u201cAcho que a gente passou para o Dudu, acho que a gente deu umas sete ou foi dez, coisa assim, nem lembro. Teve a dos informantes que a gente passou. Deu pra ele, n\u00e9? Pagou com material, tinha demais\u201d, diz.\nAs conversas tamb\u00e9m indicam que Everton orientava que a droga fosse escondida e guardada at\u00e9 a falta do produto no mercado ilegal, como forma de influenciar o valor da venda e que a estrat\u00e9gia precisaria ser discutida com outras pessoas envolvidas, incluindo o delegado Braz Marroni.\n\u201cQualquer coisa tamb\u00e9m est\u00e1 guardadinha. O grosso ficou com a gente. Quando ele queimar a deles, a gente joga a da gente. Eu deixei entucada. E antes eu tenho que conversar com o povo, saber se todo mundo aceita, sentar para combinar o que vem, o prazo que vem o resto, principalmente por causa do delegado, que est\u00e1 nisso tamb\u00e9m. Eles s\u00e3o chatos, ficam enchendo o saco\u201d.\nInvestigados t\u00eam pris\u00e3o tempor\u00e1ria prorrogada\nA Justi\u00e7a da Para\u00edba prorrogou por mais 30 dias a pris\u00e3o tempor\u00e1ria do delegado Braz Morroni, dos agentes da Pol\u00edcia Civil Everton Aires e Eduardo Jorge, e de outros sete investigados presos durante a Opera\u00e7\u00e3o Perf\u00eddus, que apura suspeita de liga\u00e7\u00e3o com o tr\u00e1fico de drogas. A decis\u00e3o aponta que o prazo inicial foi considerado insuficiente para a an\u00e1lise completa de celulares, computadores e outros materiais apreendidos.\nNa mesma decis\u00e3o, a Justi\u00e7a negou o pedido de pris\u00e3o domiciliar apresentado pela defesa de Braz Morroni, mas determinou que o investigado receba acompanhamento m\u00e9dico na unidade prisional. A defesa informou que ir\u00e1 recorrer por meio de habeas corpus.\nO despacho tamb\u00e9m manteve o bloqueio de contas banc\u00e1rias de Everton Aires e Eduardo Jorge, conhecido como \"M\u00e3o Branca\" e determinou que a Pol\u00edcia Civil conclua as per\u00edcias e apresente o relat\u00f3rio final do inqu\u00e9rito dentro do novo prazo. \nO g1 n\u00e3o conseguiu novo contato com as defesas de 'Bomba' e 'M\u00e3o Branca'.\nOs investigados permanecem presos no Pres\u00eddio Especial do Valentina, em Jo\u00e3o Pessoa.\nOpera\u00e7\u00e3o Perf\u00eddus\nA opera\u00e7\u00e3o investiga uma organiza\u00e7\u00e3o criminosa suspeita de envolvimento com tr\u00e1fico de drogas, corrup\u00e7\u00e3o e vazamento de informa\u00e7\u00f5es sigilosas. Ao todo, est\u00e3o sendo cumpridos nove mandados de pris\u00e3o e 24 mandados de busca e apreens\u00e3o. A Justi\u00e7a tamb\u00e9m determinou o bloqueio de cerca de R$ 10 milh\u00f5es dos investigados.\nUm dos agentes presos \u00e9 Everton Rychelyson da Silva Aires, conhecido como \"Bomba\" ou \"Bombado\". De acordo com a Pol\u00edcia Civil, ele \u00e9 apontado como operador central da organiza\u00e7\u00e3o e fazia a ponte entre policiais e traficantes.\nO segundo agente \u00e9 Eduardo Jorge Ferreira do Egito, conhecido como \"M\u00e3o Branca\". O investigador \u00e9 apontado como participante direto de subtra\u00e7\u00f5es de drogas e teria monitorado carregamentos, utilizado rastreadores e escondido drogas em casa.\nOutros presos da opera\u00e7\u00e3o:\nJo\u00e3o Wicttor Alves de Lima;\nBrendo Roberth Fernandes Sobral;\nPaulo Ricardo Barbosa de Souza (\"Galinha\");\nJos\u00e9 Alexandrino de Lira J\u00fanior (\"J\u00fanior Lira\");\nVanessa Dantas Fernandes;\nDankennedy Vieira Brito da Silva (\"Babau\").\nAs defesas dos suspeitos n\u00e3o foram localizadas.\nQuem \u00e9 o delegado Braz Morroni\nDelegado Braz Morroni\nReprodu\u00e7\u00e3o \/ TV Cabo Branco\nO delegado Braz Morroni atua na Delegacia de Crimes Contra o Patrim\u00f4nio (DCCPAT), em Jo\u00e3o Pessoa. Com mais de 20 anos de carreira, o delegado j\u00e1 passou por outras delegacias, como a de Repress\u00e3o a Entorpecentes.\nSegundo as investiga\u00e7\u00f5es, a organiza\u00e7\u00e3o criminosa contaria com a participa\u00e7\u00e3o de agentes p\u00fablicos que utilizavam a estrutura do Estado para favorecer atividades criminosas. O nome da opera\u00e7\u00e3o, Perf\u00eddia, significa \"trai\u00e7\u00e3o\" ou \"deslealdade\" e faz refer\u00eancia \u00e0 conduta atribu\u00edda aos investigados.\nV\u00eddeos mais assistidos do g1 Para\u00edba  ","protected":false},"excerpt":{"rendered":"<p>        Policiais envolvidos com o tr\u00e1fico de drogas planejavam acabar com a Draco<br \/>\n Um dos \u00e1udios da investiga\u00e7\u00e3o que resultou na pris\u00e3o do delegado Braz Morroni, de dois agentes da Pol\u00edcia Civil e de outros sete investigados mostra um dos agentes pres&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[34],"tags":[35],"class_list":["post-68475","post","type-post","status-publish","format-standard","hentry","category-g1","tag-g1"],"author_meta":{"display_name":"g1 &gt; Para\u00edba","author_link":"https:\/\/sindaopcpb.org.br\/author\/g1-paraiba\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/g1\/\" class=\"advgb-post-tax-term\">G1<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">G1<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/g1\/\" class=\"advgb-post-tax-term\">g1<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">g1<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 2 semanas atr\u00e1s","modified":"Atualizado 2 semanas atr\u00e1s"},"absolute_dates":{"created":"Publicado em 1 de julho de 2026","modified":"Atualizado em 1 de julho de 2026"},"absolute_dates_time":{"created":"Publicado em 1 de julho de 2026 13:09","modified":"Atualizado em 1 de julho de 2026 13:09"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/68475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=68475"}],"version-history":[{"count":1,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/68475\/revisions"}],"predecessor-version":[{"id":68476,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/68475\/revisions\/68476"}],"wp:attachment":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=68475"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=68475"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=68475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}