{"id":44165,"date":"2024-01-30T09:00:10","date_gmt":"2024-01-30T12:00:10","guid":{"rendered":"https:\/\/www.pbagora.com.br\/?p=805591"},"modified":"2024-01-30T09:00:10","modified_gmt":"2024-01-30T12:00:10","slug":"adolescente-e-assassinado-a-tiros-a-caminho-do-trabalho-no-centro-de-joao-pessoa","status":"publish","type":"post","link":"https:\/\/sindaopcpb.org.br\/index.php\/2024\/01\/30\/adolescente-e-assassinado-a-tiros-a-caminho-do-trabalho-no-centro-de-joao-pessoa\/","title":{"rendered":"Adolescente \u00e9 assassinado a tiros a caminho do trabalho no Centro de Jo\u00e3o Pessoa"},"content":{"rendered":"<p><img width=\"939\" height=\"430\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/30084000\/Sem-titulo-25.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" style=\"margin-bottom: 20px;\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/30084000\/Sem-titulo-25.jpg 939w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/30084000\/Sem-titulo-25-300x137.jpg 300w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/30084000\/Sem-titulo-25-150x69.jpg 150w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/30084000\/Sem-titulo-25-768x352.jpg 768w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/30084000\/Sem-titulo-25-380x174.jpg 380w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/30084000\/Sem-titulo-25-800x366.jpg 800w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/30084000\/Sem-titulo-25-80x37.jpg 80w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/30084000\/Sem-titulo-25-760x348.jpg 760w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/30084000\/Sem-titulo-25-600x275.jpg 600w\" sizes=\"(max-width: 939px) 100vw, 939px\" \/><\/p><p>Um jovem de 23 anos foi morto a tiros quando estava a caminho do trabalho, em Jo\u00e3o Pessoa. O crime aconteceu na noite de ontem (29) na rua Diogo Velho, no Centro. Segundo a Pol\u00edcia Civil, a v\u00edtima estava em uma bicicleta quando foi morto. Segundo informa\u00e7\u00f5es do delegado Bruno Victor Germano, o criminoso estaria em uma motocicleta, emparelhou o ve\u00edculo com a v\u00edtima e atirou diversas vezes.<\/p>\n<p>O jovem n\u00e3o resistiu aos ferimentos e morreu no local. A Pol\u00edcia Civil deve investigar o caso na tentativa de identificar o respons\u00e1vel e a motiva\u00e7\u00e3o do crime. Quem tiver informa\u00e7\u00f5es verdadeiras que possam ajudar o trabalho investigativo, pode ligar para o disque-den\u00fancia 197. N\u00e3o \u00e9 preciso se identificar.<\/p>\n<p>Reda\u00e7\u00e3o<\/p>\n","protected":false},"excerpt":{"rendered":"<p><img decoding=\"async\" width=\"939\" height=\"430\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/30084000\/Sem-titulo-25.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" loading=\"lazy\"><\/p>\n<p>Um jovem de 23 anos foi morto a tiros quando estava a caminho do trabalho, em Jo\u00e3o Pessoa.\u2026<\/p>\n","protected":false},"author":123457,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[34,66,10827],"tags":[35],"class_list":["post-44165","post","type-post","status-publish","format-standard","hentry","category-g1","category-policial","category-rodape-02","tag-g1"],"author_meta":{"display_name":"Reda\u00e7\u00e3o","author_link":"https:\/\/sindaopcpb.org.br\/author\/redacao\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/g1\/\" class=\"advgb-post-tax-term\">G1<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">Policial<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/rodape-02\/\" class=\"advgb-post-tax-term\">Rodape 02<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">G1<\/span>","<span class=\"advgb-post-tax-term\">Policial<\/span>","<span class=\"advgb-post-tax-term\">Rodape 02<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/rodape-02\/\" class=\"advgb-post-tax-term\">g1<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">g1<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 2 anos atr\u00e1s","modified":"Atualizado 2 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 30 de janeiro de 2024","modified":"Atualizado em 30 de janeiro de 2024"},"absolute_dates_time":{"created":"Publicado em 30 de janeiro de 2024 09:00","modified":"Atualizado em 30 de janeiro de 2024 09:00"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/44165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/users\/123457"}],"replies":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=44165"}],"version-history":[{"count":1,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/44165\/revisions"}],"predecessor-version":[{"id":44167,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/44165\/revisions\/44167"}],"wp:attachment":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=44165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=44165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=44165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}