{"id":44134,"date":"2024-01-29T12:00:18","date_gmt":"2024-01-29T15:00:18","guid":{"rendered":"https:\/\/www.pbagora.com.br\/?p=805380"},"modified":"2024-01-29T12:00:18","modified_gmt":"2024-01-29T15:00:18","slug":"final-de-semana-tem-mais-de-130-conduzidos-para-delegacias-e-21-armas-apreendidas-na-pb","status":"publish","type":"post","link":"https:\/\/sindaopcpb.org.br\/index.php\/2024\/01\/29\/final-de-semana-tem-mais-de-130-conduzidos-para-delegacias-e-21-armas-apreendidas-na-pb\/","title":{"rendered":"Final de semana tem mais de 130 conduzidos para delegacias e 21 armas apreendidas na PB"},"content":{"rendered":"<p><img width=\"687\" height=\"463\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/10\/28090335\/csm_foto_da_viatura_pmpb_80863bb6aa.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"\" style=\"margin-bottom: 20px;\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/10\/28090335\/csm_foto_da_viatura_pmpb_80863bb6aa.webp 687w, https:\/\/pbagora.s3.amazonaws.com\/2023\/10\/28090335\/csm_foto_da_viatura_pmpb_80863bb6aa-300x202.webp 300w, https:\/\/pbagora.s3.amazonaws.com\/2023\/10\/28090335\/csm_foto_da_viatura_pmpb_80863bb6aa-150x101.webp 150w, https:\/\/pbagora.s3.amazonaws.com\/2023\/10\/28090335\/csm_foto_da_viatura_pmpb_80863bb6aa-380x256.webp 380w, https:\/\/pbagora.s3.amazonaws.com\/2023\/10\/28090335\/csm_foto_da_viatura_pmpb_80863bb6aa-80x54.webp 80w, https:\/\/pbagora.s3.amazonaws.com\/2023\/10\/28090335\/csm_foto_da_viatura_pmpb_80863bb6aa-600x404.webp 600w\" sizes=\"(max-width: 687px) 100vw, 687px\" \/><\/p><p>O refor\u00e7o do policiamento e intensifica\u00e7\u00e3o das a\u00e7\u00f5es preventivas da Pol\u00edcia Militar neste \u00faltimo final de semana (26 a 28), durante a Opera\u00e7\u00e3o Ver\u00e3o, resultaram na condu\u00e7\u00e3o de 132 pessoas para as delegacias por diversos delitos na Para\u00edba. Nas a\u00e7\u00f5es, 21 armas de fogo que circulavam ilegalmente tamb\u00e9m foram apreendidas.<\/p>\n<p>O dado foi apresentado em um relat\u00f3rio do Estado-Maior Estrat\u00e9gico da corpora\u00e7\u00e3o, que fez um balan\u00e7o das a\u00e7\u00f5es entre as 13h da sexta-feira (26) at\u00e9 as 23h59 do domingo (28). Entre os presos, est\u00e3o acusados de tr\u00e1fico de drogas, crimes patrimoniais, porte e posse ilegal de arma de fogo, amea\u00e7a, viol\u00eancia dom\u00e9stica, foragidos da Justi\u00e7a com mandados de pris\u00e3o em aberto, adolescentes que cometeram atos infracionais, entre outros.<\/p>\n<p>No per\u00edodo, 26 ve\u00edculos que haviam sido furtados ou roubados foram recuperados, e mais de dois quilos de drogas foram apreendidas. De sexta at\u00e9 o domingo, as a\u00e7\u00f5es se concentraram em 129 munic\u00edpios, onde a PM abordou mais de 5600 pessoas, 3500 carros e motos, realizando 220 blitzen com fiscaliza\u00e7\u00f5es no tr\u00e2nsito. Nos eventos de Ver\u00e3o na regi\u00e3o metropolitana de Jo\u00e3o Pessoa n\u00e3o foram registradas ocorr\u00eancias graves. <\/p>\n<p>Ainda de acordo com o balan\u00e7o, 1.035 ocorr\u00eancias policiais foram atendidas por meio do 190, levando ao emprego de quase tr\u00eas mil policiais e 1.067 viaturas. <\/p>\n<p><strong>PB Agora<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p><img decoding=\"async\" width=\"687\" height=\"463\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/10\/28090335\/csm_foto_da_viatura_pmpb_80863bb6aa.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"\" loading=\"lazy\"><\/p>\n<p>O refor\u00e7o do policiamento e intensifica\u00e7\u00e3o das a\u00e7\u00f5es preventivas da Pol\u00edcia Militar neste \u00faltimo final de semana (26\u2026<\/p>\n","protected":false},"author":123457,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[34,66,10824],"tags":[35],"class_list":["post-44134","post","type-post","status-publish","format-standard","hentry","category-g1","category-policial","category-principal3","tag-g1"],"author_meta":{"display_name":"Reda\u00e7\u00e3o","author_link":"https:\/\/sindaopcpb.org.br\/author\/redacao\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/g1\/\" class=\"advgb-post-tax-term\">G1<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">Policial<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/principal3\/\" class=\"advgb-post-tax-term\">Principal3<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">G1<\/span>","<span class=\"advgb-post-tax-term\">Policial<\/span>","<span class=\"advgb-post-tax-term\">Principal3<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/principal3\/\" class=\"advgb-post-tax-term\">g1<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">g1<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 2 anos atr\u00e1s","modified":"Atualizado 2 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 29 de janeiro de 2024","modified":"Atualizado em 29 de janeiro de 2024"},"absolute_dates_time":{"created":"Publicado em 29 de janeiro de 2024 12:00","modified":"Atualizado em 29 de janeiro de 2024 12:00"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/44134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/users\/123457"}],"replies":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=44134"}],"version-history":[{"count":1,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/44134\/revisions"}],"predecessor-version":[{"id":44135,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/44134\/revisions\/44135"}],"wp:attachment":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=44134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=44134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=44134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}