{"id":44018,"date":"2024-01-25T09:13:44","date_gmt":"2024-01-25T12:13:44","guid":{"rendered":"https:\/\/www.pbagora.com.br\/?p=804502"},"modified":"2024-01-25T11:00:44","modified_gmt":"2024-01-25T14:00:44","slug":"homem-vende-caminhao-para-investir-em-cocaina-e-acaba-preso-em-joao-pessoa","status":"publish","type":"post","link":"https:\/\/sindaopcpb.org.br\/index.php\/2024\/01\/25\/homem-vende-caminhao-para-investir-em-cocaina-e-acaba-preso-em-joao-pessoa\/","title":{"rendered":"Homem vende caminh\u00e3o para \u201cinvestir\u201d em coca\u00edna e acaba preso em Jo\u00e3o Pessoa"},"content":{"rendered":"<p><img width=\"721\" height=\"505\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/25091334\/presocomdrogas.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"\" style=\"margin-bottom: 20px;\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/25091334\/presocomdrogas.webp 721w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/25091334\/presocomdrogas-300x210.webp 300w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/25091334\/presocomdrogas-150x105.webp 150w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/25091334\/presocomdrogas-380x266.webp 380w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/25091334\/presocomdrogas-80x56.webp 80w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/25091334\/presocomdrogas-600x420.webp 600w\" sizes=\"(max-width: 721px) 100vw, 721px\" \/><\/p><p>Na noite de quarta-feira (25), um homem foi detido na Perimetral Sul, em Jo\u00e3o Pessoa, ap\u00f3s ser encontrado na posse de 10 tabletes de coca\u00edna, estimados em R$ 300 mil.<\/p>\n<p>Ap\u00f3s ser conduzido \u00e0 Cidade da Pol\u00edcia Civil, o suspeito alegou ter vendido um caminh\u00e3o ca\u00e7amba por R$ 100 mil e &#8216;investido&#8217; o dinheiro na compra da droga com o intuito de obter lucro.<\/p>\n<p>Agentes da For\u00e7a Regional, ao avistarem o homem dentro de um ve\u00edculo na Perimetral Sul, consideraram sua conduta suspeita e procederam a uma busca no autom\u00f3vel, resultando na descoberta da subst\u00e2ncia il\u00edcita.<\/p>\n<p>Este n\u00e3o \u00e9 o primeiro envolvimento do suspeito com o tr\u00e1fico de drogas, visto que j\u00e1 havia sido detido anteriormente por essa pr\u00e1tica. Al\u00e9m da droga, durante a revista, tamb\u00e9m foram apreendidos um rev\u00f3lver e um carregador de pistola calibre .40.<\/p>\n<p><strong>PB Agora<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p><img decoding=\"async\" width=\"721\" height=\"505\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/25091334\/presocomdrogas.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"\" loading=\"lazy\"><\/p>\n<p>Na noite de quarta-feira (25), um homem foi detido na Perimetral Sul, em Jo\u00e3o Pessoa, ap\u00f3s ser encontrado\u2026<\/p>\n","protected":false},"author":123457,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[34,66,10807],"tags":[35],"class_list":["post-44018","post","type-post","status-publish","format-standard","hentry","category-g1","category-policial","category-rodape-01","tag-g1"],"author_meta":{"display_name":"Reda\u00e7\u00e3o","author_link":"https:\/\/sindaopcpb.org.br\/author\/redacao\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/g1\/\" class=\"advgb-post-tax-term\">G1<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">Policial<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/rodape-01\/\" class=\"advgb-post-tax-term\">Rodape 01<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">G1<\/span>","<span class=\"advgb-post-tax-term\">Policial<\/span>","<span class=\"advgb-post-tax-term\">Rodape 01<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/rodape-01\/\" class=\"advgb-post-tax-term\">g1<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">g1<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 3 anos atr\u00e1s","modified":"Atualizado 3 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 25 de janeiro de 2024","modified":"Atualizado em 25 de janeiro de 2024"},"absolute_dates_time":{"created":"Publicado em 25 de janeiro de 2024 09:13","modified":"Atualizado em 25 de janeiro de 2024 11:00"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/44018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/users\/123457"}],"replies":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=44018"}],"version-history":[{"count":2,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/44018\/revisions"}],"predecessor-version":[{"id":44026,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/44018\/revisions\/44026"}],"wp:attachment":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=44018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=44018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=44018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}