{"id":43964,"date":"2024-01-23T16:03:10","date_gmt":"2024-01-23T19:03:10","guid":{"rendered":"https:\/\/www.pbagora.com.br\/?p=804065"},"modified":"2024-01-23T16:03:10","modified_gmt":"2024-01-23T19:03:10","slug":"mulher-em-situacao-de-vulnerabilidade-e-resgatada-pela-prf-na-br-230-em-campina-grande-pb","status":"publish","type":"post","link":"https:\/\/sindaopcpb.org.br\/index.php\/2024\/01\/23\/mulher-em-situacao-de-vulnerabilidade-e-resgatada-pela-prf-na-br-230-em-campina-grande-pb\/","title":{"rendered":"Mulher em situa\u00e7\u00e3o de vulnerabilidade \u00e9 resgatada pela PRF na BR-230 em Campina Grande-PB"},"content":{"rendered":"<p><img width=\"1024\" height=\"576\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/23143043\/WhatsApp-Image-2024-01-23-at-14.29.11-1024x576.jpeg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" style=\"margin-bottom: 20px;\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/23143043\/WhatsApp-Image-2024-01-23-at-14.29.11-1024x576.jpeg 1024w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/23143043\/WhatsApp-Image-2024-01-23-at-14.29.11-300x169.jpeg 300w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/23143043\/WhatsApp-Image-2024-01-23-at-14.29.11-150x84.jpeg 150w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/23143043\/WhatsApp-Image-2024-01-23-at-14.29.11-768x432.jpeg 768w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/23143043\/WhatsApp-Image-2024-01-23-at-14.29.11-1536x864.jpeg 1536w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/23143043\/WhatsApp-Image-2024-01-23-at-14.29.11-380x214.jpeg 380w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/23143043\/WhatsApp-Image-2024-01-23-at-14.29.11-800x450.jpeg 800w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/23143043\/WhatsApp-Image-2024-01-23-at-14.29.11-1160x652.jpeg 1160w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/23143043\/WhatsApp-Image-2024-01-23-at-14.29.11-80x46.jpeg 80w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/23143043\/WhatsApp-Image-2024-01-23-at-14.29.11-760x427.jpeg 760w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/23143043\/WhatsApp-Image-2024-01-23-at-14.29.11-600x337.jpeg 600w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/23143043\/WhatsApp-Image-2024-01-23-at-14.29.11.jpeg 1599w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p><p><em>A mulher caminhava trajando apenas uma toalha de banho. Ela teria sa\u00eddo de Jo\u00e3o Pessoa, litoral paraibano, com destino a Campina Grande, agreste do estado<\/em><\/p>\n<p>Uma a\u00e7\u00e3o humanit\u00e1ria da Pol\u00edcia Rodovi\u00e1ria Federal (PRF) na Para\u00edba em a\u00e7\u00e3o conjunta com o Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia (SAMU), resultou no resgate de uma senhora de 57 anos em situa\u00e7\u00e3o de extrema vulnerabilidade. O incidente ocorreu na manh\u00e3 desta ter\u00e7a-feira (23), por volta das 11h, quando os agentes da PRF realizavam fiscaliza\u00e7\u00e3o de rotina na BR-230, pr\u00f3ximo \u00e0 Unidade Operacional (UOP) da PRF no munic\u00edpio de Campina Grande-PB e encontraram a mulher seminua \u00e0s margens da rodovia, desamparada, desorientada, faminta e em condi\u00e7\u00f5es prec\u00e1rias.<\/p>\n<p>Ao avistarem a senhora em estado de vulnerabilidade trajando apenas uma toalha de banho, agentes da PRF imediatamente acolheram ela na UOP, sendo oferecida \u00e1gua e comida. A mulher, que estava com a pele avermelhada devido ao sol, apresentava sinais aparentes de insola\u00e7\u00e3o. Contudo, ela conseguiu relatar que estava caminhando de Jo\u00e3o Pessoa-PB com destino a Campina Grande-PB, onde supostamente sobrevive nas ruas h\u00e1 dez anos. Ela n\u00e3o soube informar nenhum telefone de familiar para contato.<\/p>\n<p>Uma ambul\u00e2ncia do SAMU foi chamada para prestar os primeiros socorros e encaminh\u00e1-la ao atendimento m\u00e9dico adequado. A senhora foi prontamente levada ao Hospital Dr. Edgley, situado no munic\u00edpio de Campina Grande-PB. O hospital \u00e9 refer\u00eancia na regi\u00e3o e conta com uma equipe multidisciplinar preparada para lidar com situa\u00e7\u00f5es de emerg\u00eancia e casos delicados. A equipe m\u00e9dica e assistencial do hospital est\u00e1 trabalhando em conjunto com as autoridades para reunir informa\u00e7\u00f5es sobre seu hist\u00f3rico e circunst\u00e2ncias que a levaram a essa condi\u00e7\u00e3o. O caso refor\u00e7a a import\u00e2ncia da atua\u00e7\u00e3o integrada entre os \u00f3rg\u00e3os de seguran\u00e7a e sa\u00fade para lidar com situa\u00e7\u00f5es emergenciais e socorrer aqueles em situa\u00e7\u00e3o de vulnerabilidade.<\/p>\n<p>A PRF refor\u00e7a sua miss\u00e3o fundamental de salvar vidas ao protagonizar esse resgate. A a\u00e7\u00e3o evidencia a abordagem integral da PRF, que vai al\u00e9m da seguran\u00e7a vi\u00e1ria, buscando tamb\u00e9m a preserva\u00e7\u00e3o do bem-estar e da dignidade humana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/23143043\/WhatsApp-Image-2024-01-23-at-14.29.11-1024x576.jpeg\" class=\"attachment-large size-large wp-post-image\" alt=\"\"><\/p>\n<p>A mulher caminhava trajando apenas uma toalha de banho. Ela teria sa\u00eddo de Jo\u00e3o Pessoa, litoral paraibano, com\u2026<\/p>\n","protected":false},"author":123457,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[34,66],"tags":[35],"class_list":["post-43964","post","type-post","status-publish","format-standard","hentry","category-g1","category-policial","tag-g1"],"author_meta":{"display_name":"Reda\u00e7\u00e3o","author_link":"https:\/\/sindaopcpb.org.br\/author\/redacao\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/g1\/\" class=\"advgb-post-tax-term\">G1<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">Policial<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">G1<\/span>","<span class=\"advgb-post-tax-term\">Policial<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">g1<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">g1<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 2 anos atr\u00e1s","modified":"Atualizado 2 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 23 de janeiro de 2024","modified":"Atualizado em 23 de janeiro de 2024"},"absolute_dates_time":{"created":"Publicado em 23 de janeiro de 2024 16:03","modified":"Atualizado em 23 de janeiro de 2024 16:03"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/users\/123457"}],"replies":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=43964"}],"version-history":[{"count":2,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43964\/revisions"}],"predecessor-version":[{"id":43975,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43964\/revisions\/43975"}],"wp:attachment":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=43964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=43964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=43964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}