{"id":43925,"date":"2024-01-22T11:00:56","date_gmt":"2024-01-22T14:00:56","guid":{"rendered":"https:\/\/www.pbagora.com.br\/?p=803677"},"modified":"2024-01-22T11:00:56","modified_gmt":"2024-01-22T14:00:56","slug":"criminosos-explodem-cofre-de-posto-de-combustivel-na-cidade-de-remigio-durante-a-madrugada","status":"publish","type":"post","link":"https:\/\/sindaopcpb.org.br\/index.php\/2024\/01\/22\/criminosos-explodem-cofre-de-posto-de-combustivel-na-cidade-de-remigio-durante-a-madrugada\/","title":{"rendered":"Criminosos explodem cofre de posto de combust\u00edvel na cidade de Rem\u00edgio, durante a madrugada"},"content":{"rendered":"<p><img width=\"768\" height=\"432\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/22101012\/Posto-1-768x432-1.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" style=\"margin-bottom: 20px;\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/22101012\/Posto-1-768x432-1.png 768w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/22101012\/Posto-1-768x432-1-300x169.png 300w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/22101012\/Posto-1-768x432-1-150x84.png 150w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/22101012\/Posto-1-768x432-1-380x214.png 380w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/22101012\/Posto-1-768x432-1-80x46.png 80w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/22101012\/Posto-1-768x432-1-760x428.png 760w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/22101012\/Posto-1-768x432-1-600x338.png 600w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/p><p>Durante a madrugada desta segunda-feira (22), criminosos realizaram a explos\u00e3o de um posto de combust\u00edvel localizado na cidade de Rem\u00edgio, distante cerca de 140 quil\u00f4metros da Capital paraibana.<\/p>\n<p>Conforme informa\u00e7\u00f5es preliminares, o grupo utilizou explosivos para ter acesso ao cofre do estabelecimento, resultando em danos significativos \u00e0 estrutura do posto. A pol\u00edcia realiza buscas na regi\u00e3o para identificar e capturar os respons\u00e1veis pelo ataque.<\/p>\n<p>At\u00e9 o momento desta publica\u00e7\u00e3o, n\u00e3o h\u00e1 informa\u00e7\u00f5es dispon\u00edveis sobre se valores foram subtra\u00eddos durante o ato criminoso.<\/p>\n<p><strong>PB Agora<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"432\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/22101012\/Posto-1-768x432-1.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\"><\/p>\n<p>Durante a madrugada desta segunda-feira (22), criminosos realizaram a explos\u00e3o de um posto de combust\u00edvel localizado na cidade\u2026<\/p>\n","protected":false},"author":123457,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[34,66,10824],"tags":[35],"class_list":["post-43925","post","type-post","status-publish","format-standard","hentry","category-g1","category-policial","category-principal3","tag-g1"],"author_meta":{"display_name":"Reda\u00e7\u00e3o","author_link":"https:\/\/sindaopcpb.org.br\/author\/redacao\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/g1\/\" class=\"advgb-post-tax-term\">G1<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">Policial<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/principal3\/\" class=\"advgb-post-tax-term\">Principal3<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">G1<\/span>","<span class=\"advgb-post-tax-term\">Policial<\/span>","<span class=\"advgb-post-tax-term\">Principal3<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/principal3\/\" class=\"advgb-post-tax-term\">g1<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">g1<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 2 anos atr\u00e1s","modified":"Atualizado 2 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 22 de janeiro de 2024","modified":"Atualizado em 22 de janeiro de 2024"},"absolute_dates_time":{"created":"Publicado em 22 de janeiro de 2024 11:00","modified":"Atualizado em 22 de janeiro de 2024 11:00"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/users\/123457"}],"replies":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=43925"}],"version-history":[{"count":2,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43925\/revisions"}],"predecessor-version":[{"id":43936,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43925\/revisions\/43936"}],"wp:attachment":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=43925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=43925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=43925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}