{"id":43738,"date":"2024-01-15T07:58:36","date_gmt":"2024-01-15T10:58:36","guid":{"rendered":"https:\/\/www.pbagora.com.br\/?p=802349"},"modified":"2024-01-15T07:58:36","modified_gmt":"2024-01-15T10:58:36","slug":"dois-apenados-que-descumpriram-liberdade-condicional-sao-recapturados-em-jp","status":"publish","type":"post","link":"https:\/\/sindaopcpb.org.br\/index.php\/2024\/01\/15\/dois-apenados-que-descumpriram-liberdade-condicional-sao-recapturados-em-jp\/","title":{"rendered":"Dois apenados que descumpriram liberdade condicional s\u00e3o recapturados em JP"},"content":{"rendered":"<p><img width=\"687\" height=\"463\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/10\/28090335\/csm_foto_da_viatura_pmpb_80863bb6aa.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"\" style=\"margin-bottom: 20px;\" decoding=\"async\" srcset=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/10\/28090335\/csm_foto_da_viatura_pmpb_80863bb6aa.webp 687w, https:\/\/pbagora.s3.amazonaws.com\/2023\/10\/28090335\/csm_foto_da_viatura_pmpb_80863bb6aa-300x202.webp 300w, https:\/\/pbagora.s3.amazonaws.com\/2023\/10\/28090335\/csm_foto_da_viatura_pmpb_80863bb6aa-150x101.webp 150w, https:\/\/pbagora.s3.amazonaws.com\/2023\/10\/28090335\/csm_foto_da_viatura_pmpb_80863bb6aa-380x256.webp 380w, https:\/\/pbagora.s3.amazonaws.com\/2023\/10\/28090335\/csm_foto_da_viatura_pmpb_80863bb6aa-80x54.webp 80w, https:\/\/pbagora.s3.amazonaws.com\/2023\/10\/28090335\/csm_foto_da_viatura_pmpb_80863bb6aa-600x404.webp 600w\" sizes=\"(max-width: 687px) 100vw, 687px\" \/><\/p><p>Policiais da For\u00e7a Regional prenderam dois homens que estavam descumprindo medidas da liberdade condicional, durante rondas preventivas em bairros da capital. As pris\u00f5es ocorreram durante o fim de semana.<\/p>\n<p>Os apenados foram localizados nos bairros de Jardim Veneza e Mana\u00edra. Ambos os presos descumpriram medidas da liberdade condicional, devendo estar em casa aos finais de semana. Um dos apenados possui tr\u00eas passagens por roubo. Os presos foram conduzidos \u00e0s unidades penitenci\u00e1rias.<\/p>\n<p><strong>PB Agora<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" width=\"687\" height=\"463\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/10\/28090335\/csm_foto_da_viatura_pmpb_80863bb6aa.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"\"><\/p>\n<p>Policiais da For\u00e7a Regional prenderam dois homens que estavam descumprindo medidas da liberdade condicional, durante rondas preventivas em\u2026<\/p>\n","protected":false},"author":123457,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[10806,34,66],"tags":[35],"class_list":["post-43738","post","type-post","status-publish","format-standard","hentry","category-destaque-centro-03","category-g1","category-policial","tag-g1"],"author_meta":{"display_name":"Reda\u00e7\u00e3o","author_link":"https:\/\/sindaopcpb.org.br\/author\/redacao\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/destaque-centro-03\/\" class=\"advgb-post-tax-term\">Destaque Centro 03<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/g1\/\" class=\"advgb-post-tax-term\">G1<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">Policial<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Destaque Centro 03<\/span>","<span class=\"advgb-post-tax-term\">G1<\/span>","<span class=\"advgb-post-tax-term\">Policial<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">g1<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">g1<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 2 anos atr\u00e1s","modified":"Atualizado 2 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 15 de janeiro de 2024","modified":"Atualizado em 15 de janeiro de 2024"},"absolute_dates_time":{"created":"Publicado em 15 de janeiro de 2024 07:58","modified":"Atualizado em 15 de janeiro de 2024 07:58"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/users\/123457"}],"replies":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=43738"}],"version-history":[{"count":2,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43738\/revisions"}],"predecessor-version":[{"id":43750,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43738\/revisions\/43750"}],"wp:attachment":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=43738"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=43738"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=43738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}