{"id":43585,"date":"2024-01-10T14:54:51","date_gmt":"2024-01-10T17:54:51","guid":{"rendered":"https:\/\/www.pbagora.com.br\/?p=801604"},"modified":"2024-01-10T14:54:51","modified_gmt":"2024-01-10T17:54:51","slug":"pm-desarticula-esquema-interestadual-de-roubo-e-clonagem-de-veiculos-na-grande-joao-pessoa","status":"publish","type":"post","link":"https:\/\/sindaopcpb.org.br\/index.php\/2024\/01\/10\/pm-desarticula-esquema-interestadual-de-roubo-e-clonagem-de-veiculos-na-grande-joao-pessoa\/","title":{"rendered":"PM desarticula esquema interestadual de roubo e clonagem de ve\u00edculos na Grande Jo\u00e3o Pessoa"},"content":{"rendered":"<p><img width=\"768\" height=\"571\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/10145441\/ESQUEMA_CRIMINOSO-4.jpeg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" style=\"margin-bottom: 20px;\" decoding=\"async\" srcset=\"https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/10145441\/ESQUEMA_CRIMINOSO-4.jpeg 768w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/10145441\/ESQUEMA_CRIMINOSO-4-300x223.jpeg 300w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/10145441\/ESQUEMA_CRIMINOSO-4-150x112.jpeg 150w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/10145441\/ESQUEMA_CRIMINOSO-4-200x150.jpeg 200w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/10145441\/ESQUEMA_CRIMINOSO-4-380x283.jpeg 380w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/10145441\/ESQUEMA_CRIMINOSO-4-80x58.jpeg 80w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/10145441\/ESQUEMA_CRIMINOSO-4-760x565.jpeg 760w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/10145441\/ESQUEMA_CRIMINOSO-4-600x446.jpeg 600w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/p><p>A Pol\u00edcia Militar desarticulou um esquema criminoso de carros roubados, e que tinha por objetivo montar clones dos ve\u00edculos, ou desmanch\u00e1-los. As a\u00e7\u00f5es ocorreram entre a noite da \u00faltima ter\u00e7a-feira (09) e manh\u00e3 desta quarta (10) na grande Jo\u00e3o Pessoa. Um criminoso foi preso.<\/p>\n<p>De acordo com o Grupamento de A\u00e7\u00f5es T\u00e1ticas Especiais (Gate), o principal acusado j\u00e1 tinha passagem por tentativa de latroc\u00ednio e estava respondendo em regime domiciliar. \u201cEle foi encontrado com um carro clonado, ve\u00edculo Gol que era roubado mas que possu\u00eda caracter\u00edsticas adulteradas sendo semelhante a outro em situa\u00e7\u00e3o legal. A abordagem foi no bairro de Colinas do Sul, ainda durante a tarde de ter\u00e7a\u201d, explicou o major Carlos, subcomandante do Gate.<\/p>\n<p>Segundo a unidade, durante as dilig\u00eancias a PM chegou a outro ve\u00edculo roubado, uma L200, e a dois galp\u00f5es usados para o esquema criminoso de adultera\u00e7\u00e3o e clonagem de ve\u00edculos. J\u00e1 nesta quarta, outro galp\u00e3o usado por criminosos foi localizado no munic\u00edpio de Bayeux, e duas pessoas foram conduzidas para prestarem esclarecimentos. \u201cO homem preso ontem tamb\u00e9m nos relatou que o esquema criminoso seria interestadual, algo que ser\u00e1 apurado na investiga\u00e7\u00e3o\u201d, disse o major.<\/p>\n<p>Ao todo, a PM identificou seis ve\u00edculos roubados ou furtados, que estavam desmontados nos galp\u00f5es. A ocorr\u00eancia foi apresentada na Delegacia de Roubos e Furtos de Ve\u00edculos, onde ser\u00e1 investigada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"571\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/10145441\/ESQUEMA_CRIMINOSO-4.jpeg\" class=\"attachment-large size-large wp-post-image\" alt=\"\"><\/p>\n<p>A Pol\u00edcia Militar desarticulou um esquema criminoso de carros roubados, e que tinha por objetivo montar clones dos\u2026<\/p>\n","protected":false},"author":123458,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[34,66,10824],"tags":[35],"class_list":["post-43585","post","type-post","status-publish","format-standard","hentry","category-g1","category-policial","category-principal3","tag-g1"],"author_meta":{"display_name":"Feliphe Rojas","author_link":"https:\/\/sindaopcpb.org.br\/author\/feliphe-rojas\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/g1\/\" class=\"advgb-post-tax-term\">G1<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">Policial<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/principal3\/\" class=\"advgb-post-tax-term\">Principal3<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">G1<\/span>","<span class=\"advgb-post-tax-term\">Policial<\/span>","<span class=\"advgb-post-tax-term\">Principal3<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/principal3\/\" class=\"advgb-post-tax-term\">g1<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">g1<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 3 anos atr\u00e1s","modified":"Atualizado 3 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 10 de janeiro de 2024","modified":"Atualizado em 10 de janeiro de 2024"},"absolute_dates_time":{"created":"Publicado em 10 de janeiro de 2024 14:54","modified":"Atualizado em 10 de janeiro de 2024 14:54"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/users\/123458"}],"replies":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=43585"}],"version-history":[{"count":2,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43585\/revisions"}],"predecessor-version":[{"id":43593,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43585\/revisions\/43593"}],"wp:attachment":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=43585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=43585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=43585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}