{"id":43573,"date":"2024-01-10T09:00:12","date_gmt":"2024-01-10T12:00:12","guid":{"rendered":"https:\/\/www.pbagora.com.br\/?p=801493"},"modified":"2024-01-10T09:00:12","modified_gmt":"2024-01-10T12:00:12","slug":"corpo-de-mulher-com-sinais-de-violencia-sexual-e-encontrado-em-terreno-baldio-em-santa-rita","status":"publish","type":"post","link":"https:\/\/sindaopcpb.org.br\/index.php\/2024\/01\/10\/corpo-de-mulher-com-sinais-de-violencia-sexual-e-encontrado-em-terreno-baldio-em-santa-rita\/","title":{"rendered":"Corpo de mulher com sinais de viol\u00eancia sexual \u00e9 encontrado em terreno baldio, em Santa Rita"},"content":{"rendered":"<p><img width=\"800\" height=\"532\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/10085102\/Design-sem-nome-10-1.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"\" style=\"margin-bottom: 20px;\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/10085102\/Design-sem-nome-10-1.webp 800w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/10085102\/Design-sem-nome-10-1-300x200.webp 300w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/10085102\/Design-sem-nome-10-1-150x100.webp 150w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/10085102\/Design-sem-nome-10-1-768x511.webp 768w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/10085102\/Design-sem-nome-10-1-380x253.webp 380w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/10085102\/Design-sem-nome-10-1-80x53.webp 80w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/10085102\/Design-sem-nome-10-1-760x505.webp 760w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/10085102\/Design-sem-nome-10-1-600x399.webp 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p><p>Nessa ter\u00e7a-feira (09), o corpo de uma mulher, identificada como Rosineide Barbosa da Silva, de 59 anos, foi encontrado em um terreno baldio no bairro Marcos Moura, em Santa Rita, na Grande Jo\u00e3o Pessoa. A v\u00edtima estava desaparecida desde o domingo passado (07), quando saiu de casa ap\u00f3s receber uma liga\u00e7\u00e3o de um homem desconhecido.<\/p>\n<p>A per\u00edcia da Pol\u00edcia Civil constatou que o corpo da mulher j\u00e1 se encontrava em estado de decomposi\u00e7\u00e3o, apresentando ind\u00edcios de viol\u00eancia sexual. Ela foi descoberta sem a parte inferior das roupas. O perito Igor Ramalho afirmou que coletas foram realizadas para exames que esclarecer\u00e3o a causa da morte.<\/p>\n<p>A irm\u00e3 da v\u00edtima, respons\u00e1vel por registrar o boletim de ocorr\u00eancia pelo desaparecimento, relatou que Rosineide tinha o h\u00e1bito de sair com amigos para beber e que recebeu uma liga\u00e7\u00e3o por volta da meia-noite de domingo, convidando-a para sair. No entanto, ela n\u00e3o p\u00f4de identificar o autor da liga\u00e7\u00e3o nem para onde a irm\u00e3 foi.<\/p>\n<p>A delegacia de homic\u00eddios da Pol\u00edcia Civil est\u00e1 conduzindo as investiga\u00e7\u00f5es para identificar o suspeito do crime. O corpo da mulher foi recolhido pelo Instituto de Pol\u00edcia Cient\u00edfica (IPC).<\/p>\n<p><strong>PB Agora<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p><img decoding=\"async\" width=\"800\" height=\"532\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/10085102\/Design-sem-nome-10-1.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"\" loading=\"lazy\"><\/p>\n<p>Nessa ter\u00e7a-feira (09), o corpo de uma mulher, identificada como Rosineide Barbosa da Silva, de 59 anos, foi\u2026<\/p>\n","protected":false},"author":123457,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[10823,34,66],"tags":[35],"class_list":["post-43573","post","type-post","status-publish","format-standard","hentry","category-destaque-centro-01","category-g1","category-policial","tag-g1"],"author_meta":{"display_name":"Reda\u00e7\u00e3o","author_link":"https:\/\/sindaopcpb.org.br\/author\/redacao\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/destaque-centro-01\/\" class=\"advgb-post-tax-term\">Destaque Centro 01<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/g1\/\" class=\"advgb-post-tax-term\">G1<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">Policial<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Destaque Centro 01<\/span>","<span class=\"advgb-post-tax-term\">G1<\/span>","<span class=\"advgb-post-tax-term\">Policial<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">g1<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">g1<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 2 anos atr\u00e1s","modified":"Atualizado 2 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 10 de janeiro de 2024","modified":"Atualizado em 10 de janeiro de 2024"},"absolute_dates_time":{"created":"Publicado em 10 de janeiro de 2024 09:00","modified":"Atualizado em 10 de janeiro de 2024 09:00"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/users\/123457"}],"replies":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=43573"}],"version-history":[{"count":1,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43573\/revisions"}],"predecessor-version":[{"id":43574,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43573\/revisions\/43574"}],"wp:attachment":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=43573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=43573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=43573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}