{"id":43553,"date":"2024-01-09T17:55:59","date_gmt":"2024-01-09T20:55:59","guid":{"rendered":"https:\/\/www.pbagora.com.br\/?p=801403"},"modified":"2024-01-09T17:55:59","modified_gmt":"2024-01-09T20:55:59","slug":"suspeito-de-tentar-matar-esposa-a-facadas-se-apresenta-a-policia-3o-caso-em-tres-dias-na-pb","status":"publish","type":"post","link":"https:\/\/sindaopcpb.org.br\/index.php\/2024\/01\/09\/suspeito-de-tentar-matar-esposa-a-facadas-se-apresenta-a-policia-3o-caso-em-tres-dias-na-pb\/","title":{"rendered":"Suspeito de tentar matar esposa a facadas se apresenta \u00e0 pol\u00edcia; 3\u00ba caso em tr\u00eas dias na PB"},"content":{"rendered":"<p><img width=\"1024\" height=\"678\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/07\/21111915\/entrega_viatura_patrulha_13_anos_lei_maria_da_penha_gov_07_08_19_4-1024x678.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" style=\"margin-bottom: 20px;\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/07\/21111915\/entrega_viatura_patrulha_13_anos_lei_maria_da_penha_gov_07_08_19_4-1024x678.jpg 1024w, https:\/\/pbagora.s3.amazonaws.com\/2023\/07\/21111915\/entrega_viatura_patrulha_13_anos_lei_maria_da_penha_gov_07_08_19_4-300x199.jpg 300w, https:\/\/pbagora.s3.amazonaws.com\/2023\/07\/21111915\/entrega_viatura_patrulha_13_anos_lei_maria_da_penha_gov_07_08_19_4-150x99.jpg 150w, https:\/\/pbagora.s3.amazonaws.com\/2023\/07\/21111915\/entrega_viatura_patrulha_13_anos_lei_maria_da_penha_gov_07_08_19_4-768x509.jpg 768w, https:\/\/pbagora.s3.amazonaws.com\/2023\/07\/21111915\/entrega_viatura_patrulha_13_anos_lei_maria_da_penha_gov_07_08_19_4-1536x1018.jpg 1536w, https:\/\/pbagora.s3.amazonaws.com\/2023\/07\/21111915\/entrega_viatura_patrulha_13_anos_lei_maria_da_penha_gov_07_08_19_4-380x252.jpg 380w, https:\/\/pbagora.s3.amazonaws.com\/2023\/07\/21111915\/entrega_viatura_patrulha_13_anos_lei_maria_da_penha_gov_07_08_19_4-800x530.jpg 800w, https:\/\/pbagora.s3.amazonaws.com\/2023\/07\/21111915\/entrega_viatura_patrulha_13_anos_lei_maria_da_penha_gov_07_08_19_4-1160x769.jpg 1160w, https:\/\/pbagora.s3.amazonaws.com\/2023\/07\/21111915\/entrega_viatura_patrulha_13_anos_lei_maria_da_penha_gov_07_08_19_4-80x53.jpg 80w, https:\/\/pbagora.s3.amazonaws.com\/2023\/07\/21111915\/entrega_viatura_patrulha_13_anos_lei_maria_da_penha_gov_07_08_19_4-760x504.jpg 760w, https:\/\/pbagora.s3.amazonaws.com\/2023\/07\/21111915\/entrega_viatura_patrulha_13_anos_lei_maria_da_penha_gov_07_08_19_4-600x398.jpg 600w, https:\/\/pbagora.s3.amazonaws.com\/2023\/07\/21111915\/entrega_viatura_patrulha_13_anos_lei_maria_da_penha_gov_07_08_19_4.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p><p>Na tarde desta ter\u00e7a-feira (9), se apresentou \u00e0 pol\u00edcia o homem suspeito de tentar matar esposa a facadas na noite do \u00faltimo domingo (7) em um bar no munic\u00edpio de S\u00e3o Miguel de Taipu, na Zona da Mata paraibana.<\/p>\n<p>Segundo as investiga\u00e7\u00f5es, a tentativa de feminic\u00eddio teria sido motivada porque, segundo o suspeito, sua esposa teria pego R$ 40 que pertenciam a ele.<\/p>\n<p>O casal estava em um bar por volta das 21h quando, de repente, segundo testemunhas, o suspeito puxou uma faca e passou a agredir sua esposa.<\/p>\n<p>Ferida, a mulher foi socorrida para uma unidade hospitalar em S\u00e3o Miguel de Taipu, mas logo em seguida foi transferida para o Hospital de Emerg\u00eancia e Trauma de Jo\u00e3o Pessoa.<\/p>\n<p>Ainda segundo a pol\u00edcia, mesmo ap\u00f3s receber alta, a mulher n\u00e3o prestou queixa contra o acusado. A pol\u00edcia realizou dilig\u00eancias, mas n\u00e3o conseguiu captur\u00e1-lo. Entretanto, nesta ter\u00e7a, o indiv\u00edduo se apresentou na Delegacia do munic\u00edpio de Pilar, onde teria permanecido em sil\u00eancio.<\/p>\n<p><strong>TENTATIVAS DE FEMINIC\u00cdDIO<\/strong><\/p>\n<p>Este \u00e9 mais um de tr\u00eas casos registrados pela pol\u00edcia da para\u00edba desde o \u00faltimo domingo at\u00e9 esta ter\u00e7a.<\/p>\n<p>Na manh\u00e3 desta segunda-feira (8), uma mulher foi v\u00edtima de um disparo de arma de fogo na cabe\u00e7a. O tiro teria sido disparado pelo ex-esposo. O crime aconteceu no bairro de Jaguaribe, em Jo\u00e3o Pessoa. O homem foi preso na cidade de Itaporanga. A v\u00edtima segue internada em estado grave no Hospital de Trauma da Capital.<\/p>\n<p>A outra ocorr\u00eancia aconteceu na cidade de Juazeirinho quando um homem de 37 anos teria agredido sua companheira, uma adolescente de apenas 17 anos. Ele foi preso no munic\u00edpio de Cubati, onde aguarda audi\u00eancia de cust\u00f3dia.<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>PB Agora<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p><img decoding=\"async\" width=\"1024\" height=\"678\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/07\/21111915\/entrega_viatura_patrulha_13_anos_lei_maria_da_penha_gov_07_08_19_4-1024x678.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" loading=\"lazy\"><\/p>\n<p>Na tarde desta ter\u00e7a-feira (9), se apresentou \u00e0 pol\u00edcia o homem suspeito de tentar matar esposa a facadas\u2026<\/p>\n","protected":false},"author":123457,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[10826,34,66],"tags":[35],"class_list":["post-43553","post","type-post","status-publish","format-standard","hentry","category-destaque-centro-02","category-g1","category-policial","tag-g1"],"author_meta":{"display_name":"Reda\u00e7\u00e3o","author_link":"https:\/\/sindaopcpb.org.br\/author\/redacao\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/destaque-centro-02\/\" class=\"advgb-post-tax-term\">Destaque Centro 02<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/g1\/\" class=\"advgb-post-tax-term\">G1<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">Policial<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Destaque Centro 02<\/span>","<span class=\"advgb-post-tax-term\">G1<\/span>","<span class=\"advgb-post-tax-term\">Policial<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">g1<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">g1<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 2 anos atr\u00e1s","modified":"Atualizado 2 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 9 de janeiro de 2024","modified":"Atualizado em 9 de janeiro de 2024"},"absolute_dates_time":{"created":"Publicado em 9 de janeiro de 2024 17:55","modified":"Atualizado em 9 de janeiro de 2024 17:55"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/users\/123457"}],"replies":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=43553"}],"version-history":[{"count":1,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43553\/revisions"}],"predecessor-version":[{"id":43554,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43553\/revisions\/43554"}],"wp:attachment":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=43553"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=43553"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=43553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}