{"id":43551,"date":"2024-01-09T18:00:23","date_gmt":"2024-01-09T21:00:23","guid":{"rendered":"https:\/\/www.pbagora.com.br\/?p=801394"},"modified":"2024-01-09T18:00:23","modified_gmt":"2024-01-09T21:00:23","slug":"apos-quatro-meses-internado-por-tiro-na-cabeca-mingau-baixista-do-ultraje-a-rigor-recebe-alta","status":"publish","type":"post","link":"https:\/\/sindaopcpb.org.br\/index.php\/2024\/01\/09\/apos-quatro-meses-internado-por-tiro-na-cabeca-mingau-baixista-do-ultraje-a-rigor-recebe-alta\/","title":{"rendered":"Ap\u00f3s quatro meses internado por tiro na cabe\u00e7a, Mingau, baixista do Ultraje a Rigor, recebe alta"},"content":{"rendered":"<p><img width=\"665\" height=\"502\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/09161659\/mingau.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" style=\"margin-bottom: 20px;\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/09161659\/mingau.jpg 665w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/09161659\/mingau-300x226.jpg 300w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/09161659\/mingau-150x113.jpg 150w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/09161659\/mingau-200x150.jpg 200w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/09161659\/mingau-260x195.jpg 260w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/09161659\/mingau-380x287.jpg 380w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/09161659\/mingau-80x60.jpg 80w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/09161659\/mingau-600x453.jpg 600w\" sizes=\"(max-width: 665px) 100vw, 665px\" \/><\/p><p>O baixista Mingau, da banda Ultraje a Rigor, recebeu alta ap\u00f3s quatro meses de interna\u00e7\u00e3o no Hospital S\u00e3o Luiz, da Rede D\u2019Or, na zona sul da capital paulista. Rinaldo Oliveira Amaral foi baleado na cabe\u00e7a, em Paraty (RJ), no dia 2 de setembro de 2023.<\/p>\n<p>Ap\u00f3s receber os primeiros atendimentos no local, foi transferido para o hospital paulistano. No S\u00e3o Luiz, passou por tr\u00eas cirurgias e tratou de uma infec\u00e7\u00e3o. De acordo com nota divulgada pelo hospital, o paciente \u201creuniu condi\u00e7\u00f5es de alta com seguran\u00e7a\u201d e seguir\u00e1 o tratamento para reabilita\u00e7\u00e3o em uma cl\u00ednica.<\/p>\n<p>Ainda de acordo como o comunicado do hospital, Mingau n\u00e3o est\u00e1 mais sedado, respira espontaneamente e tem \u201cboa evolu\u00e7\u00e3o do quadro neurol\u00f3gico\u201d.<\/p>\n<p>Dois suspeitos de envolvimento na a\u00e7\u00e3o que feriu o m\u00fasico foram presos.<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>Ag\u00eancia Brasil<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p><img decoding=\"async\" width=\"665\" height=\"502\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/09161659\/mingau.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" loading=\"lazy\"><\/p>\n<p>O baixista Mingau, da banda Ultraje a Rigor, recebeu alta ap\u00f3s quatro meses de interna\u00e7\u00e3o no Hospital S\u00e3o\u2026<\/p>\n","protected":false},"author":123457,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[10806,34,66],"tags":[35],"class_list":["post-43551","post","type-post","status-publish","format-standard","hentry","category-destaque-centro-03","category-g1","category-policial","tag-g1"],"author_meta":{"display_name":"Reda\u00e7\u00e3o","author_link":"https:\/\/sindaopcpb.org.br\/author\/redacao\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/destaque-centro-03\/\" class=\"advgb-post-tax-term\">Destaque Centro 03<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/g1\/\" class=\"advgb-post-tax-term\">G1<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">Policial<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Destaque Centro 03<\/span>","<span class=\"advgb-post-tax-term\">G1<\/span>","<span class=\"advgb-post-tax-term\">Policial<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">g1<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">g1<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 2 anos atr\u00e1s","modified":"Atualizado 2 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 9 de janeiro de 2024","modified":"Atualizado em 9 de janeiro de 2024"},"absolute_dates_time":{"created":"Publicado em 9 de janeiro de 2024 18:00","modified":"Atualizado em 9 de janeiro de 2024 18:00"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/users\/123457"}],"replies":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=43551"}],"version-history":[{"count":1,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43551\/revisions"}],"predecessor-version":[{"id":43552,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43551\/revisions\/43552"}],"wp:attachment":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=43551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=43551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=43551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}