{"id":43544,"date":"2024-01-09T16:00:42","date_gmt":"2024-01-09T19:00:42","guid":{"rendered":"https:\/\/www.pbagora.com.br\/?p=801377"},"modified":"2024-01-09T18:50:42","modified_gmt":"2024-01-09T21:50:42","slug":"preso-em-itaporanga-homem-que-atirou-na-cabeca-da-ex-companheira-na-capital-vitima-segue-em-estado-grave","status":"publish","type":"post","link":"https:\/\/sindaopcpb.org.br\/index.php\/2024\/01\/09\/preso-em-itaporanga-homem-que-atirou-na-cabeca-da-ex-companheira-na-capital-vitima-segue-em-estado-grave\/","title":{"rendered":"Preso em Itaporanga homem que atirou na cabe\u00e7a da ex-companheira na Capital; v\u00edtima segue em estado grave"},"content":{"rendered":"<p><img width=\"719\" height=\"472\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/09101725\/hyldinho02_1704806161738-e1704806266902.jpeg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" style=\"margin-bottom: 20px;\" decoding=\"async\" srcset=\"https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/09101725\/hyldinho02_1704806161738-e1704806266902.jpeg 719w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/09101725\/hyldinho02_1704806161738-e1704806266902-300x197.jpeg 300w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/09101725\/hyldinho02_1704806161738-e1704806266902-150x98.jpeg 150w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/09101725\/hyldinho02_1704806161738-e1704806266902-380x249.jpeg 380w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/09101725\/hyldinho02_1704806161738-e1704806266902-80x53.jpeg 80w, https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/09101725\/hyldinho02_1704806161738-e1704806266902-600x394.jpeg 600w\" sizes=\"(max-width: 719px) 100vw, 719px\" \/><\/p><p>Ap\u00f3s buscas intensas, foi preso, no in\u00edcio da tarde desta ter\u00e7a-feira (9), o o homem suspeito de atirar contra a ex-companheira na \u00faltima segunda-feira (8). Ele foi identificado pelo nome de Fabiano Gomes.<\/p>\n<p>O crime aconteceu em frente ao Hospital Napole\u00e3o Laureano, no bairro Jaguaribe, em Jo\u00e3o Pessoa. Imagens de c\u00e2meras de monitoramento identificaram o suspeito fugindo ap\u00f3s o crime.<\/p>\n<p><strong>Entenda:<\/strong><br \/>\n<strong><a href=\"https:\/\/www.pbagora.com.br\/noticia\/policial\/policia-identifica-mulher-que-sofreu-ataque-a-tiros-no-bairro-de-jaguaribe-em-joao-pessoa\/\">Pol\u00edcia identifica mulher que sofreu ataque a tiros no bairro de Jaguaribe, em JP<\/a><\/strong><\/p>\n<p>Com base nas imagens e com o apoio de informa\u00e7\u00f5es da popula\u00e7\u00e3o, a pol\u00edcia conseguiu chegar ao suspeito e prend\u00ea-lo no munic\u00edpio de Itaporanga, na regi\u00e3o do Vale do Pianc\u00f3.<\/p>\n<p>Leia tamb\u00e9m:<br \/>\n<a href=\"https:\/\/www.pbagora.com.br\/noticia\/policial\/policia-identifica-homem-que-atirou-na-cabeca-de-ex-mulher-em-jaguaribe-e-intensifica-buscas\/\"><strong>Pol\u00edcia identifica homem que atirou na cabe\u00e7a de ex-mulher em Jaguaribe e intensifica buscas<\/strong><\/a><\/p>\n<p>Ele estava dentro de da casa que possui na cidade. Den\u00fancias an\u00f4nimas levaram policiais civis e militares at\u00e9 o local.<\/p>\n<p>A v\u00edtima, identificada como Ver\u00f4nica Mendes de Lima Gomes, de 49 anos, foi socorrida para o Hospital de Emerg\u00eancia e Trauma da Capital, onde permanece internada em estado grave. Ela foi atingida na cabe\u00e7a pelo disparo.<\/p>\n<p>Detido, o homem aguarda audi\u00eancia de cust\u00f3dia. Ele deve responder pelo crime de tentativa de feminic\u00eddio.<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>PB Agora<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" width=\"719\" height=\"472\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/09101725\/hyldinho02_1704806161738-e1704806266902.jpeg\" class=\"attachment-large size-large wp-post-image\" alt=\"\"><\/p>\n<p>Ap\u00f3s buscas intensas, foi preso, no in\u00edcio da tarde desta ter\u00e7a-feira (9), o o homem suspeito de atirar\u2026<\/p>\n","protected":false},"author":123457,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[34,66,10824],"tags":[35],"class_list":["post-43544","post","type-post","status-publish","format-standard","hentry","category-g1","category-policial","category-principal3","tag-g1"],"author_meta":{"display_name":"Reda\u00e7\u00e3o","author_link":"https:\/\/sindaopcpb.org.br\/author\/redacao\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/g1\/\" class=\"advgb-post-tax-term\">G1<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">Policial<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/principal3\/\" class=\"advgb-post-tax-term\">Principal3<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">G1<\/span>","<span class=\"advgb-post-tax-term\">Policial<\/span>","<span class=\"advgb-post-tax-term\">Principal3<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/principal3\/\" class=\"advgb-post-tax-term\">g1<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">g1<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 2 anos atr\u00e1s","modified":"Atualizado 2 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 9 de janeiro de 2024","modified":"Atualizado em 9 de janeiro de 2024"},"absolute_dates_time":{"created":"Publicado em 9 de janeiro de 2024 16:00","modified":"Atualizado em 9 de janeiro de 2024 18:50"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/users\/123457"}],"replies":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=43544"}],"version-history":[{"count":4,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43544\/revisions"}],"predecessor-version":[{"id":43561,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43544\/revisions\/43561"}],"wp:attachment":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=43544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=43544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=43544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}