{"id":43507,"date":"2024-01-08T13:11:42","date_gmt":"2024-01-08T16:11:42","guid":{"rendered":"https:\/\/www.pbagora.com.br\/?p=801077"},"modified":"2024-01-08T15:10:42","modified_gmt":"2024-01-08T18:10:42","slug":"quatro-pessoas-sao-presas-e-27-autuadas-por-embriaguez-ao-volante-no-1a-final-de-semana-de-2024-em-jp","status":"publish","type":"post","link":"https:\/\/sindaopcpb.org.br\/index.php\/2024\/01\/08\/quatro-pessoas-sao-presas-e-27-autuadas-por-embriaguez-ao-volante-no-1a-final-de-semana-de-2024-em-jp\/","title":{"rendered":"Quatro pessoas s\u00e3o presas e 27 autuadas por embriaguez ao volante no 1\u00aa final de semana de 2024 em JP"},"content":{"rendered":"<p><img width=\"907\" height=\"1024\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/08115026\/unnamed-55-907x1024.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" style=\"margin-bottom: 20px;\" decoding=\"async\" loading=\"lazy\" \/><\/p><p>A Opera\u00e7\u00e3o \u00c1lcool Zero, realizada pelo Batalh\u00e3o de Pol\u00edcia de Tr\u00e2nsito (BPTran), autuou 27 condutores de ve\u00edculos por dirigirem com sintomas de embriaguez, no primeiro fim de semana do ano, em Jo\u00e3o Pessoa. Cinco pessoas foram presas por essa pr\u00e1tica. Ainda nos bloqueios de fiscaliza\u00e7\u00e3o, quatro ve\u00edculos roubados foram recuperados.<\/p>\n<p>O trabalho tem o objetivo de prevenir mortes no tr\u00e2nsito, j\u00e1 que a mistura de \u00e1lcool e dire\u00e7\u00e3o tem sido uma das maiores causas. As equipes de fiscaliza\u00e7\u00e3o s\u00e3o posicionadas em locais estrat\u00e9gicos com etil\u00f4metro (comumente chamado de aparelho do teste de baf\u00f4metro). Quem recusa o teste que permite certificar influ\u00eancia de \u00e1lcool ou outra subst\u00e2ncia psicoativa, \u00e9 autuado e tem as penalidades previstas no artigo 165-A do C\u00f3digo de Tr\u00e2nsito Brasileiro (CTB).<\/p>\n","protected":false},"excerpt":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" width=\"907\" height=\"1024\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2024\/01\/08115026\/unnamed-55-907x1024.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\"><\/p>\n<p>A Opera\u00e7\u00e3o \u00c1lcool Zero, realizada pelo Batalh\u00e3o de Pol\u00edcia de Tr\u00e2nsito (BPTran), autuou 27 condutores de ve\u00edculos por\u2026<\/p>\n","protected":false},"author":123458,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[10806,34,66],"tags":[35],"class_list":["post-43507","post","type-post","status-publish","format-standard","hentry","category-destaque-centro-03","category-g1","category-policial","tag-g1"],"author_meta":{"display_name":"Feliphe Rojas","author_link":"https:\/\/sindaopcpb.org.br\/author\/feliphe-rojas\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/destaque-centro-03\/\" class=\"advgb-post-tax-term\">Destaque Centro 03<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/g1\/\" class=\"advgb-post-tax-term\">G1<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">Policial<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Destaque Centro 03<\/span>","<span class=\"advgb-post-tax-term\">G1<\/span>","<span class=\"advgb-post-tax-term\">Policial<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">g1<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">g1<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 2 anos atr\u00e1s","modified":"Atualizado 2 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 8 de janeiro de 2024","modified":"Atualizado em 8 de janeiro de 2024"},"absolute_dates_time":{"created":"Publicado em 8 de janeiro de 2024 13:11","modified":"Atualizado em 8 de janeiro de 2024 15:10"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/users\/123458"}],"replies":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=43507"}],"version-history":[{"count":3,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43507\/revisions"}],"predecessor-version":[{"id":43521,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43507\/revisions\/43521"}],"wp:attachment":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=43507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=43507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=43507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}