{"id":43252,"date":"2023-12-29T12:19:13","date_gmt":"2023-12-29T15:19:13","guid":{"rendered":"https:\/\/www.pbagora.com.br\/?p=799308"},"modified":"2023-12-29T13:44:13","modified_gmt":"2023-12-29T16:44:13","slug":"secretario-jean-nunes-assegura-operacao-ostensiva-para-garantir-seguranca-nas-festividades-de-fim-de-ano-e-veraneio-na-paraiba","status":"publish","type":"post","link":"https:\/\/sindaopcpb.org.br\/index.php\/2023\/12\/29\/secretario-jean-nunes-assegura-operacao-ostensiva-para-garantir-seguranca-nas-festividades-de-fim-de-ano-e-veraneio-na-paraiba\/","title":{"rendered":"Jean Nunes assegura opera\u00e7\u00e3o ostensiva para garantir seguran\u00e7a nas festividades de fim de ano e veraneio na PB"},"content":{"rendered":"<p><img width=\"696\" height=\"439\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2021\/12\/14133945\/Jean-Nunes-e1609187988520.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" style=\"margin-bottom: 20px;\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/pbagora.s3.amazonaws.com\/2021\/12\/14133945\/Jean-Nunes-e1609187988520.jpg 696w, https:\/\/pbagora.s3.amazonaws.com\/2021\/12\/14133945\/Jean-Nunes-e1609187988520-300x189.jpg 300w, https:\/\/pbagora.s3.amazonaws.com\/2021\/12\/14133945\/Jean-Nunes-e1609187988520-150x95.jpg 150w, https:\/\/pbagora.s3.amazonaws.com\/2021\/12\/14133945\/Jean-Nunes-e1609187988520-380x240.jpg 380w, https:\/\/pbagora.s3.amazonaws.com\/2021\/12\/14133945\/Jean-Nunes-e1609187988520-80x50.jpg 80w, https:\/\/pbagora.s3.amazonaws.com\/2021\/12\/14133945\/Jean-Nunes-e1609187988520-600x378.jpg 600w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/p><p>Nesta sexta-feira (29), o secret\u00e1rio de Seguran\u00e7a P\u00fablica e Defesa Social, Jean Nunes, fez um balan\u00e7o positivo das a\u00e7\u00f5es desenvolvidas pela pasta ao longo do ano. Em entrevista \u00e0 R\u00e1dio Arapuan FM, Nunes destacou os progressos alcan\u00e7ados e expressou otimismo em rela\u00e7\u00e3o \u00e0s conquistas previstas para 2024.<\/p>\n<p>&#8220;Foi um ano muito promissor, muita coisa boa, a chegada de nova tecnologia, novos servidores, novos concursos, muita coisa em andamento que deve acontecer agora em 2024&#8221;, afirmou o secret\u00e1rio.<\/p>\n<p>Ao abordar o esquema de seguran\u00e7a para as festividades de fim de ano e o per\u00edodo de veraneio no estado, Jean Nunes assegurou que as for\u00e7as policiais est\u00e3o prontas e atuando de forma ostensiva para garantir a tranquilidade dos moradores e turistas que escolhem a Para\u00edba como destino nesse per\u00edodo.<\/p>\n<p>Quanto \u00e0s expectativas para o pr\u00f3ximo ano, o secret\u00e1rio destacou que o maior desafio \u00e9 a redu\u00e7\u00e3o ainda mais expressiva dos \u00edndices de criminalidade no estado.<\/p>\n<p><strong>PB Agora<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" width=\"696\" height=\"439\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2021\/12\/14133945\/Jean-Nunes-e1609187988520.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\"><\/p>\n<p>Nesta sexta-feira (29), o secret\u00e1rio de Seguran\u00e7a P\u00fablica e Defesa Social, Jean Nunes, fez um balan\u00e7o positivo das\u2026<\/p>\n","protected":false},"author":123457,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[34,66,10822],"tags":[35],"class_list":["post-43252","post","type-post","status-publish","format-standard","hentry","category-g1","category-policial","category-principal2","tag-g1"],"author_meta":{"display_name":"Reda\u00e7\u00e3o","author_link":"https:\/\/sindaopcpb.org.br\/author\/redacao\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/g1\/\" class=\"advgb-post-tax-term\">G1<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">Policial<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/principal2\/\" class=\"advgb-post-tax-term\">Principal2<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">G1<\/span>","<span class=\"advgb-post-tax-term\">Policial<\/span>","<span class=\"advgb-post-tax-term\">Principal2<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/principal2\/\" class=\"advgb-post-tax-term\">g1<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">g1<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 2 anos atr\u00e1s","modified":"Atualizado 2 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 29 de dezembro de 2023","modified":"Atualizado em 29 de dezembro de 2023"},"absolute_dates_time":{"created":"Publicado em 29 de dezembro de 2023 12:19","modified":"Atualizado em 29 de dezembro de 2023 13:44"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/users\/123457"}],"replies":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=43252"}],"version-history":[{"count":4,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43252\/revisions"}],"predecessor-version":[{"id":43274,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43252\/revisions\/43274"}],"wp:attachment":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=43252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=43252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=43252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}