{"id":43134,"date":"2023-12-25T12:12:49","date_gmt":"2023-12-25T15:12:49","guid":{"rendered":"https:\/\/www.pbagora.com.br\/?p=798482"},"modified":"2023-12-25T12:12:49","modified_gmt":"2023-12-25T15:12:49","slug":"policia-prende-homem-por-porte-ilegal-de-arma-em-lagoa","status":"publish","type":"post","link":"https:\/\/sindaopcpb.org.br\/index.php\/2023\/12\/25\/policia-prende-homem-por-porte-ilegal-de-arma-em-lagoa\/","title":{"rendered":"Pol\u00edcia prende homem por porte ilegal de arma em Lagoa"},"content":{"rendered":"<p><img width=\"921\" height=\"744\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/25113752\/unnamed-2023-12-25T113728.499.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" style=\"margin-bottom: 20px;\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/25113752\/unnamed-2023-12-25T113728.499.jpg 921w, https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/25113752\/unnamed-2023-12-25T113728.499-300x242.jpg 300w, https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/25113752\/unnamed-2023-12-25T113728.499-150x121.jpg 150w, https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/25113752\/unnamed-2023-12-25T113728.499-768x620.jpg 768w, https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/25113752\/unnamed-2023-12-25T113728.499-380x307.jpg 380w, https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/25113752\/unnamed-2023-12-25T113728.499-800x646.jpg 800w, https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/25113752\/unnamed-2023-12-25T113728.499-80x65.jpg 80w, https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/25113752\/unnamed-2023-12-25T113728.499-760x614.jpg 760w, https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/25113752\/unnamed-2023-12-25T113728.499-600x485.jpg 600w\" sizes=\"(max-width: 921px) 100vw, 921px\" \/><\/p><p>Policiais militares do Batalh\u00e3o de Opera\u00e7\u00f5es Especiais (Bope) prenderam, na madrugada desta segunda-feira (25), um suspeito de porte ilegal de arma de fogo, na cidade de Lagoa. O homem foi preso ap\u00f3s uma abordagem veicular.<\/p>\n<p>As equipes do Bope realizavam rondas no trecho que liga as cidades de Lagoa e Bom Sucesso, quando visualizaram um ve\u00edculo suspeito. Na abordagem, foi encontrada uma pistola calibre 9mm, com 18 muni\u00e7\u00f5es intactas.<\/p>\n<p>O suspeito, de 33 anos, foi preso e conduzido para a delegacia da cidade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" width=\"921\" height=\"744\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/25113752\/unnamed-2023-12-25T113728.499.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\"><\/p>\n<p>Policiais militares do Batalh\u00e3o de Opera\u00e7\u00f5es Especiais (Bope) prenderam, na madrugada desta segunda-feira (25), um suspeito de porte\u2026<\/p>\n","protected":false},"author":123457,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[10826,34,66],"tags":[35],"class_list":["post-43134","post","type-post","status-publish","format-standard","hentry","category-destaque-centro-02","category-g1","category-policial","tag-g1"],"author_meta":{"display_name":"Reda\u00e7\u00e3o","author_link":"https:\/\/sindaopcpb.org.br\/author\/redacao\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/destaque-centro-02\/\" class=\"advgb-post-tax-term\">Destaque Centro 02<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/g1\/\" class=\"advgb-post-tax-term\">G1<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">Policial<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Destaque Centro 02<\/span>","<span class=\"advgb-post-tax-term\">G1<\/span>","<span class=\"advgb-post-tax-term\">Policial<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">g1<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">g1<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 2 anos atr\u00e1s","modified":"Atualizado 2 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 25 de dezembro de 2023","modified":"Atualizado em 25 de dezembro de 2023"},"absolute_dates_time":{"created":"Publicado em 25 de dezembro de 2023 12:12","modified":"Atualizado em 25 de dezembro de 2023 12:12"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/users\/123457"}],"replies":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=43134"}],"version-history":[{"count":2,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43134\/revisions"}],"predecessor-version":[{"id":43143,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43134\/revisions\/43143"}],"wp:attachment":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=43134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=43134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=43134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}