{"id":43082,"date":"2023-12-22T16:45:59","date_gmt":"2023-12-22T19:45:59","guid":{"rendered":"https:\/\/www.pbagora.com.br\/?p=798198"},"modified":"2023-12-22T16:45:59","modified_gmt":"2023-12-22T19:45:59","slug":"operacao-verao-prende-oito-na-orla-da-grande-joao-pessoa","status":"publish","type":"post","link":"https:\/\/sindaopcpb.org.br\/index.php\/2023\/12\/22\/operacao-verao-prende-oito-na-orla-da-grande-joao-pessoa\/","title":{"rendered":"Opera\u00e7\u00e3o Ver\u00e3o prende oito na orla da Grande Jo\u00e3o Pessoa"},"content":{"rendered":"<p><img width=\"1024\" height=\"682\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/19130730\/unnamed-2023-12-19T130538.787-1024x682.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" style=\"margin-bottom: 20px;\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/19130730\/unnamed-2023-12-19T130538.787-1024x682.jpg 1024w, https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/19130730\/unnamed-2023-12-19T130538.787-300x200.jpg 300w, https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/19130730\/unnamed-2023-12-19T130538.787-150x100.jpg 150w, https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/19130730\/unnamed-2023-12-19T130538.787-768x512.jpg 768w, https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/19130730\/unnamed-2023-12-19T130538.787-1536x1024.jpg 1536w, https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/19130730\/unnamed-2023-12-19T130538.787-2048x1365.jpg 2048w, https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/19130730\/unnamed-2023-12-19T130538.787-380x253.jpg 380w, https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/19130730\/unnamed-2023-12-19T130538.787-800x533.jpg 800w, https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/19130730\/unnamed-2023-12-19T130538.787-1160x773.jpg 1160w, https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/19130730\/unnamed-2023-12-19T130538.787-80x53.jpg 80w, https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/19130730\/unnamed-2023-12-19T130538.787-760x506.jpg 760w, https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/19130730\/unnamed-2023-12-19T130538.787-600x400.jpg 600w, https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/19130730\/unnamed-2023-12-19T130538.787.jpg 2560w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p><p>As a\u00e7\u00f5es da Opera\u00e7\u00e3o Ver\u00e3o na regi\u00e3o da orla da Grande Jo\u00e3o Pessoa j\u00e1 levaram \u00e0 pris\u00e3o oito pessoas acusadas de crimes patrimoniais nesta quinta-feira (21). Al\u00e9m de foragidos da Justi\u00e7a capturados, entre os presos h\u00e1 um grupo acusado de violar e furtar casas de veraneio.<\/p>\n<p>As pris\u00f5es foram realizadas pelo Batalh\u00e3o Especializado em Policiamento Tur\u00edstico (BEPTur). Na cidade de Lucena, um grupo de infratores foi desarticulado, ap\u00f3s tentar violar uma casa de veraneio. Al\u00e9m de impedir a consuma\u00e7\u00e3o do delito, a a\u00e7\u00e3o da PM recuperou os objetos que seriam levados por cinco adultos e um adolescente.<\/p>\n<p>Ainda durante a identifica\u00e7\u00e3o dos acusados, foi constatado que um deles j\u00e1 tinha um mandado de pris\u00e3o em aberto expedido pela Justi\u00e7a de Pernambuco. O foragido estava sendo procurado pelo crime de roubo. J\u00e1 no bairro do Bessa, em Jo\u00e3o Pessoa, uma mulher procurada pelos crimes de desacato e abandono de incapaz tamb\u00e9m foi localizada e presa durante uma abordagem. Ela estava com um mandado em aberto.<\/p>\n<p>\u201cAl\u00e9m dessas a\u00e7\u00f5es, resultado da intensifica\u00e7\u00e3o do policiamento da Opera\u00e7\u00e3o Ver\u00e3o, tamb\u00e9m prendemos um homem que estava com arma de fogo e uma motocicleta com restri\u00e7\u00e3o de roubo. O ve\u00edculo havia sido tomado em Jaguaribe, e foi localizado com o suspeito na regi\u00e3o do Centro de Conven\u00e7\u00f5es. Ele foi autuado por porte ilegal de arma de fogo e recepta\u00e7\u00e3o culposa\u201d, explicou o major Bruno, comandante do BEPTur.<\/p>\n<p>Os infratores presos foram apresentados nas delegacias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><img decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/19130730\/unnamed-2023-12-19T130538.787-1024x682.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" loading=\"lazy\"><\/p>\n<p>As a\u00e7\u00f5es da Opera\u00e7\u00e3o Ver\u00e3o na regi\u00e3o da orla da Grande Jo\u00e3o Pessoa j\u00e1 levaram \u00e0 pris\u00e3o oito\u2026<\/p>\n","protected":false},"author":123457,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[10826,34,66],"tags":[35],"class_list":["post-43082","post","type-post","status-publish","format-standard","hentry","category-destaque-centro-02","category-g1","category-policial","tag-g1"],"author_meta":{"display_name":"Reda\u00e7\u00e3o","author_link":"https:\/\/sindaopcpb.org.br\/author\/redacao\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/destaque-centro-02\/\" class=\"advgb-post-tax-term\">Destaque Centro 02<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/g1\/\" class=\"advgb-post-tax-term\">G1<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">Policial<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Destaque Centro 02<\/span>","<span class=\"advgb-post-tax-term\">G1<\/span>","<span class=\"advgb-post-tax-term\">Policial<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">g1<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">g1<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 2 anos atr\u00e1s","modified":"Atualizado 2 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 22 de dezembro de 2023","modified":"Atualizado em 22 de dezembro de 2023"},"absolute_dates_time":{"created":"Publicado em 22 de dezembro de 2023 16:45","modified":"Atualizado em 22 de dezembro de 2023 16:45"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/users\/123457"}],"replies":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=43082"}],"version-history":[{"count":1,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43082\/revisions"}],"predecessor-version":[{"id":43083,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43082\/revisions\/43083"}],"wp:attachment":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=43082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=43082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=43082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}