{"id":43009,"date":"2023-12-20T07:25:49","date_gmt":"2023-12-20T10:25:49","guid":{"rendered":"https:\/\/www.pbagora.com.br\/?p=797417"},"modified":"2023-12-20T09:35:49","modified_gmt":"2023-12-20T12:35:49","slug":"policia-civil-deflagra-operacao-porto-seguro-contra-homicidios-na-regiao-metropolitana-de-joao-pessoa","status":"publish","type":"post","link":"https:\/\/sindaopcpb.org.br\/index.php\/2023\/12\/20\/policia-civil-deflagra-operacao-porto-seguro-contra-homicidios-na-regiao-metropolitana-de-joao-pessoa\/","title":{"rendered":"Pol\u00edcia Civil deflagra opera\u00e7\u00e3o Porto Seguro contra homic\u00eddios na Regi\u00e3o Metropolitana de Jo\u00e3o Pessoa\u201d"},"content":{"rendered":"<p><img width=\"754\" height=\"500\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/01\/31123901\/policia-civil-padrao-2.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" style=\"margin-bottom: 20px;\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/01\/31123901\/policia-civil-padrao-2.jpg 754w, https:\/\/pbagora.s3.amazonaws.com\/2023\/01\/31123901\/policia-civil-padrao-2-300x199.jpg 300w, https:\/\/pbagora.s3.amazonaws.com\/2023\/01\/31123901\/policia-civil-padrao-2-150x99.jpg 150w, https:\/\/pbagora.s3.amazonaws.com\/2023\/01\/31123901\/policia-civil-padrao-2-380x252.jpg 380w, https:\/\/pbagora.s3.amazonaws.com\/2023\/01\/31123901\/policia-civil-padrao-2-80x53.jpg 80w, https:\/\/pbagora.s3.amazonaws.com\/2023\/01\/31123901\/policia-civil-padrao-2-600x398.jpg 600w\" sizes=\"(max-width: 754px) 100vw, 754px\" \/><\/p><p>Nesta quarta-feira (20), a Pol\u00edcia Civil da Para\u00edba deflagrou a Opera\u00e7\u00e3o Porto Seguro, executando mandados de busca e apreens\u00e3o na cidade de Cabedelo, na Regi\u00e3o Metropolitana de Jo\u00e3o Pessoa. O objetivo da a\u00e7\u00e3o, liderada pelo delegado Everaldo Medeiros, \u00e9 reunir materiais que contribuir\u00e3o nas investiga\u00e7\u00f5es de homic\u00eddios nas localidades de Bayeux, Cabedelo e na Grande Jo\u00e3o Pessoa.<\/p>\n<p>O delegado Medeiros explicou que a opera\u00e7\u00e3o visa a coleta de elementos que subsidiar\u00e3o os procedimentos em curso relacionados aos homic\u00eddios em Cabedelo. Destacou ainda que essa a\u00e7\u00e3o \u00e9 uma continuidade do trabalho realizado pela Delegacia de Repress\u00e3o ao Crime Organizado (Draco) e pelo Grupo de Opera\u00e7\u00f5es Especiais (GOE) no dia anterior (19), que resultou na apreens\u00e3o significativa de armas de fogo e muni\u00e7\u00f5es, al\u00e9m da pris\u00e3o de tr\u00eas mulheres e um homem.<\/p>\n<p>Al\u00e9m da participa\u00e7\u00e3o ativa da Pol\u00edcia Civil, a Opera\u00e7\u00e3o Porto Seguro conta com a colabora\u00e7\u00e3o da Pol\u00edcia Militar e do Corpo de Bombeiros, refor\u00e7ando o car\u00e1ter integrado da a\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><img decoding=\"async\" width=\"754\" height=\"500\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/01\/31123901\/policia-civil-padrao-2.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" loading=\"lazy\"><\/p>\n<p>Nesta quarta-feira (20), a Pol\u00edcia Civil da Para\u00edba deflagrou a Opera\u00e7\u00e3o Porto Seguro, executando mandados de busca e\u2026<\/p>\n","protected":false},"author":123457,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[10826,34,66],"tags":[35],"class_list":["post-43009","post","type-post","status-publish","format-standard","hentry","category-destaque-centro-02","category-g1","category-policial","tag-g1"],"author_meta":{"display_name":"Reda\u00e7\u00e3o","author_link":"https:\/\/sindaopcpb.org.br\/author\/redacao\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/destaque-centro-02\/\" class=\"advgb-post-tax-term\">Destaque Centro 02<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/g1\/\" class=\"advgb-post-tax-term\">G1<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">Policial<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Destaque Centro 02<\/span>","<span class=\"advgb-post-tax-term\">G1<\/span>","<span class=\"advgb-post-tax-term\">Policial<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">g1<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">g1<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 2 anos atr\u00e1s","modified":"Atualizado 2 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 20 de dezembro de 2023","modified":"Atualizado em 20 de dezembro de 2023"},"absolute_dates_time":{"created":"Publicado em 20 de dezembro de 2023 07:25","modified":"Atualizado em 20 de dezembro de 2023 09:35"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/users\/123457"}],"replies":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=43009"}],"version-history":[{"count":2,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43009\/revisions"}],"predecessor-version":[{"id":43015,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43009\/revisions\/43015"}],"wp:attachment":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=43009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=43009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=43009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}