{"id":43007,"date":"2023-12-20T07:34:37","date_gmt":"2023-12-20T10:34:37","guid":{"rendered":"https:\/\/www.pbagora.com.br\/?p=797425"},"modified":"2023-12-20T11:34:37","modified_gmt":"2023-12-20T14:34:37","slug":"homem-e-preso-suspeito-de-matar-o-namorado-no-litoral-norte-da-paraiba","status":"publish","type":"post","link":"https:\/\/sindaopcpb.org.br\/index.php\/2023\/12\/20\/homem-e-preso-suspeito-de-matar-o-namorado-no-litoral-norte-da-paraiba\/","title":{"rendered":"Homem \u00e9 preso suspeito de matar o namorado, no Litoral Norte da Para\u00edba"},"content":{"rendered":"<p><img width=\"687\" height=\"463\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/20073404\/csm_cadeia_publica_de_mamanguape_foto_facebook_7303216d03.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" style=\"margin-bottom: 20px;\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/20073404\/csm_cadeia_publica_de_mamanguape_foto_facebook_7303216d03.jpg 687w, https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/20073404\/csm_cadeia_publica_de_mamanguape_foto_facebook_7303216d03-300x202.jpg 300w, https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/20073404\/csm_cadeia_publica_de_mamanguape_foto_facebook_7303216d03-150x101.jpg 150w, https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/20073404\/csm_cadeia_publica_de_mamanguape_foto_facebook_7303216d03-380x256.jpg 380w, https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/20073404\/csm_cadeia_publica_de_mamanguape_foto_facebook_7303216d03-80x54.jpg 80w, https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/20073404\/csm_cadeia_publica_de_mamanguape_foto_facebook_7303216d03-600x404.jpg 600w\" sizes=\"(max-width: 687px) 100vw, 687px\" \/><\/p><p>Nessa ter\u00e7a-feira (19), a pol\u00edcia efetuou a pris\u00e3o de Robson Martins, de 33 anos, na cidade de Rio Tinto, no litoral norte paraibano, sob acusa\u00e7\u00f5es de ter cometido o homic\u00eddio de seu companheiro dentro da resid\u00eancia do casal. O crime, perpetrado com m\u00faltiplos tiros, teria sido motivado pela recusa em aceitar o t\u00e9rmino do relacionamento.<\/p>\n<p>O momento da deten\u00e7\u00e3o ocorreu no centro de Mamanguape, e o delegado Sylvio Rabelo, encarregado do caso, compartilhou detalhes sobre a opera\u00e7\u00e3o.<\/p>\n<p>O suspeito passou por uma audi\u00eancia de cust\u00f3dia e foi encaminhado para um dos pres\u00eddios no Vale do Mamanguape.<\/p>\n<p><strong>PB Agora<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" width=\"687\" height=\"463\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/20073404\/csm_cadeia_publica_de_mamanguape_foto_facebook_7303216d03.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\"><\/p>\n<p>Nessa ter\u00e7a-feira (19), a pol\u00edcia efetuou a pris\u00e3o de Robson Martins, de 33 anos, na cidade de Rio\u2026<\/p>\n","protected":false},"author":123457,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[34,66,10829],"tags":[35],"class_list":["post-43007","post","type-post","status-publish","format-standard","hentry","category-g1","category-policial","category-rodape-03","tag-g1"],"author_meta":{"display_name":"Reda\u00e7\u00e3o","author_link":"https:\/\/sindaopcpb.org.br\/author\/redacao\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/g1\/\" class=\"advgb-post-tax-term\">G1<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">Policial<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/rodape-03\/\" class=\"advgb-post-tax-term\">Rodape 03<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">G1<\/span>","<span class=\"advgb-post-tax-term\">Policial<\/span>","<span class=\"advgb-post-tax-term\">Rodape 03<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/rodape-03\/\" class=\"advgb-post-tax-term\">g1<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">g1<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 2 anos atr\u00e1s","modified":"Atualizado 2 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 20 de dezembro de 2023","modified":"Atualizado em 20 de dezembro de 2023"},"absolute_dates_time":{"created":"Publicado em 20 de dezembro de 2023 07:34","modified":"Atualizado em 20 de dezembro de 2023 11:34"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/users\/123457"}],"replies":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=43007"}],"version-history":[{"count":2,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43007\/revisions"}],"predecessor-version":[{"id":43018,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/43007\/revisions\/43018"}],"wp:attachment":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=43007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=43007"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=43007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}