{"id":42891,"date":"2023-12-15T12:40:03","date_gmt":"2023-12-15T15:40:03","guid":{"rendered":"https:\/\/www.pbagora.com.br\/?p=796468"},"modified":"2023-12-15T15:06:03","modified_gmt":"2023-12-15T18:06:03","slug":"delegado-de-pe-causa-tumulto-em-academia-ao-disparar-acidentalmente-arma-durante-exercicios","status":"publish","type":"post","link":"https:\/\/sindaopcpb.org.br\/index.php\/2023\/12\/15\/delegado-de-pe-causa-tumulto-em-academia-ao-disparar-acidentalmente-arma-durante-exercicios\/","title":{"rendered":"Delegado de PE causa tumulto em academia ao disparar acidentalmente arma durante exerc\u00edcios"},"content":{"rendered":"<p><img width=\"660\" height=\"530\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/15123209\/acede.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" style=\"margin-bottom: 20px;\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/15123209\/acede.jpg 660w, https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/15123209\/acede-300x241.jpg 300w, https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/15123209\/acede-150x120.jpg 150w, https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/15123209\/acede-380x305.jpg 380w, https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/15123209\/acede-80x64.jpg 80w, https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/15123209\/acede-600x482.jpg 600w\" sizes=\"(max-width: 660px) 100vw, 660px\" \/><\/p><p>Na manh\u00e3 desta sexta-feira (15), um incidente inusitado agitou uma academia no bairro de Mana\u00edra, Zona Leste de Jo\u00e3o Pessoa. De acordo com informa\u00e7\u00f5es do programa Arapuan Verdade, um delegado da Pol\u00edcia Civil de Pernambuco, identificado apenas como Fl\u00e1vio, estava realizando exerc\u00edcios f\u00edsicos quando sua arma disparou acidentalmente.<\/p>\n<p>O epis\u00f3dio provocou um corre-corre no local, uma vez que o delegado estava realizando alongamentos com a arma presa ao short. A Pol\u00edcia Civil j\u00e1 est\u00e1 investigando o ocorrido, enquanto o Batalh\u00e3o Especializado de Atendimento ao Turista (Beptur) da Pol\u00edcia Militar n\u00e3o recebeu, at\u00e9 as 11h, registros relacionados ao incidente.<\/p>\n<p>O delegado Fl\u00e1vio ser\u00e1 alvo das investiga\u00e7\u00f5es em andamento, buscando esclarecer as circunst\u00e2ncias do disparo acidental e avaliar as medidas cab\u00edveis diante do ocorrido na academia em Mana\u00edra.<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>PB Agora<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" width=\"660\" height=\"530\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/15123209\/acede.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\"><\/p>\n<p>Na manh\u00e3 desta sexta-feira (15), um incidente inusitado agitou uma academia no bairro de Mana\u00edra, Zona Leste de\u2026<\/p>\n","protected":false},"author":123457,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[34,66,10824],"tags":[35],"class_list":["post-42891","post","type-post","status-publish","format-standard","hentry","category-g1","category-policial","category-principal3","tag-g1"],"author_meta":{"display_name":"Reda\u00e7\u00e3o","author_link":"https:\/\/sindaopcpb.org.br\/author\/redacao\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/g1\/\" class=\"advgb-post-tax-term\">G1<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">Policial<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/principal3\/\" class=\"advgb-post-tax-term\">Principal3<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">G1<\/span>","<span class=\"advgb-post-tax-term\">Policial<\/span>","<span class=\"advgb-post-tax-term\">Principal3<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/principal3\/\" class=\"advgb-post-tax-term\">g1<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">g1<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 2 anos atr\u00e1s","modified":"Atualizado 2 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 15 de dezembro de 2023","modified":"Atualizado em 15 de dezembro de 2023"},"absolute_dates_time":{"created":"Publicado em 15 de dezembro de 2023 12:40","modified":"Atualizado em 15 de dezembro de 2023 15:06"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/42891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/users\/123457"}],"replies":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=42891"}],"version-history":[{"count":3,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/42891\/revisions"}],"predecessor-version":[{"id":42906,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/42891\/revisions\/42906"}],"wp:attachment":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=42891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=42891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=42891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}