{"id":42698,"date":"2023-12-08T09:28:28","date_gmt":"2023-12-08T12:28:28","guid":{"rendered":"https:\/\/www.pbagora.com.br\/?p=794896"},"modified":"2023-12-08T09:28:28","modified_gmt":"2023-12-08T12:28:28","slug":"policia-apreende-17-armas-de-fogo-e-municoes-durante-acao-em-cg","status":"publish","type":"post","link":"https:\/\/sindaopcpb.org.br\/index.php\/2023\/12\/08\/policia-apreende-17-armas-de-fogo-e-municoes-durante-acao-em-cg\/","title":{"rendered":"Pol\u00edcia apreende 17 armas de fogo e muni\u00e7\u00f5es durante a\u00e7\u00e3o em CG"},"content":{"rendered":"<p><img width=\"768\" height=\"427\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/08084657\/armas-apreendidas-768x427-1.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" style=\"margin-bottom: 20px;\" decoding=\"async\" srcset=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/08084657\/armas-apreendidas-768x427-1.jpg 768w, https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/08084657\/armas-apreendidas-768x427-1-300x167.jpg 300w, https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/08084657\/armas-apreendidas-768x427-1-150x83.jpg 150w, https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/08084657\/armas-apreendidas-768x427-1-380x211.jpg 380w, https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/08084657\/armas-apreendidas-768x427-1-80x44.jpg 80w, https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/08084657\/armas-apreendidas-768x427-1-760x423.jpg 760w, https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/08084657\/armas-apreendidas-768x427-1-600x334.jpg 600w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/p><p>A Pol\u00edcia Militar da Para\u00edba apreendeu dezessete armas de fogo e muni\u00e7\u00f5es de diversos calibres, na noite dessa quinta-feira (7) em Campina Grande, no Agreste do Estado. As armas eram de fabrica\u00e7\u00e3o artesanal e tinham marcas que representavam uma fac\u00e7\u00e3o criminosa.<\/p>\n<p>Na a\u00e7\u00e3o, os policiais militares da For\u00e7a T\u00e1tica do 2\u00ba BPM, realizavam rondas no Conjunto Moura, quando foram acionados pelo CICC (Centro Integrado de Comando e Controle) para uma averigua\u00e7\u00e3o a dois indiv\u00edduos que estavam em um ve\u00edculo preto, efetuando disparos de arma de fogo em via p\u00fablica.<\/p>\n<p>Os criminosos, ao perceberem a presen\u00e7a dos policiais, conseguiram fugir e abandonaram todo o armamento. No local, foram apreendidas: 9 espingardas, calibre 12; 1 rifle, calibre 44; 4 espingardas, calibre 28; 3 espingardas, calibre 24; al\u00e9m de muni\u00e7\u00f5es de diversos calibres. As armas, que eram de fabrica\u00e7\u00e3o artesanal, continham adesivos que as identificavam como pertencentes a uma fac\u00e7\u00e3o criminosa.<\/p>\n<p>Todo o armamento e muni\u00e7\u00f5es apreendidos foram encaminhados \u00e0 Delegacia Regional de Campina Grande. As buscas aos suspeitos foragidos continuam.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"427\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/12\/08084657\/armas-apreendidas-768x427-1.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\"><\/p>\n<p>A Pol\u00edcia Militar da Para\u00edba apreendeu dezessete armas de fogo e muni\u00e7\u00f5es de diversos calibres, na noite dessa\u2026<\/p>\n","protected":false},"author":123457,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[10826,34,66],"tags":[35],"class_list":["post-42698","post","type-post","status-publish","format-standard","hentry","category-destaque-centro-02","category-g1","category-policial","tag-g1"],"author_meta":{"display_name":"Reda\u00e7\u00e3o","author_link":"https:\/\/sindaopcpb.org.br\/author\/redacao\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/destaque-centro-02\/\" class=\"advgb-post-tax-term\">Destaque Centro 02<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/g1\/\" class=\"advgb-post-tax-term\">G1<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">Policial<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Destaque Centro 02<\/span>","<span class=\"advgb-post-tax-term\">G1<\/span>","<span class=\"advgb-post-tax-term\">Policial<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">g1<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">g1<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 3 anos atr\u00e1s","modified":"Atualizado 3 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 8 de dezembro de 2023","modified":"Atualizado em 8 de dezembro de 2023"},"absolute_dates_time":{"created":"Publicado em 8 de dezembro de 2023 09:28","modified":"Atualizado em 8 de dezembro de 2023 09:28"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/42698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/users\/123457"}],"replies":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=42698"}],"version-history":[{"count":3,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/42698\/revisions"}],"predecessor-version":[{"id":42709,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/42698\/revisions\/42709"}],"wp:attachment":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=42698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=42698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=42698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}