{"id":42647,"date":"2023-12-06T13:18:04","date_gmt":"2023-12-06T16:18:04","guid":{"rendered":"https:\/\/www.pbagora.com.br\/?p=794402"},"modified":"2023-12-06T15:00:04","modified_gmt":"2023-12-06T18:00:04","slug":"justica-determina-busca-e-apreensao-contra-seminarista-por-crime-virtual-em-seminario-da-paraiba","status":"publish","type":"post","link":"https:\/\/sindaopcpb.org.br\/index.php\/2023\/12\/06\/justica-determina-busca-e-apreensao-contra-seminarista-por-crime-virtual-em-seminario-da-paraiba\/","title":{"rendered":"Justi\u00e7a determina busca e apreens\u00e3o contra seminarista por crime virtual em Semin\u00e1rio da Para\u00edba"},"content":{"rendered":"<p><img width=\"876\" height=\"585\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2022\/04\/08075628\/arquidiocese_da_pb_walla_santos.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" style=\"margin-bottom: 20px;\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/pbagora.s3.amazonaws.com\/2022\/04\/08075628\/arquidiocese_da_pb_walla_santos.jpg 876w, https:\/\/pbagora.s3.amazonaws.com\/2022\/04\/08075628\/arquidiocese_da_pb_walla_santos-300x200.jpg 300w, https:\/\/pbagora.s3.amazonaws.com\/2022\/04\/08075628\/arquidiocese_da_pb_walla_santos-150x100.jpg 150w, https:\/\/pbagora.s3.amazonaws.com\/2022\/04\/08075628\/arquidiocese_da_pb_walla_santos-768x513.jpg 768w, https:\/\/pbagora.s3.amazonaws.com\/2022\/04\/08075628\/arquidiocese_da_pb_walla_santos-380x254.jpg 380w, https:\/\/pbagora.s3.amazonaws.com\/2022\/04\/08075628\/arquidiocese_da_pb_walla_santos-800x534.jpg 800w, https:\/\/pbagora.s3.amazonaws.com\/2022\/04\/08075628\/arquidiocese_da_pb_walla_santos-80x53.jpg 80w, https:\/\/pbagora.s3.amazonaws.com\/2022\/04\/08075628\/arquidiocese_da_pb_walla_santos-760x508.jpg 760w, https:\/\/pbagora.s3.amazonaws.com\/2022\/04\/08075628\/arquidiocese_da_pb_walla_santos-600x401.jpg 600w\" sizes=\"(max-width: 876px) 100vw, 876px\" \/><\/p><p>A Justi\u00e7a do Rio Grande do Sul emitiu um mandado de busca e apreens\u00e3o contra um seminarista da Arquidiocese da Para\u00edba, suspeito de envolvimento em atividades relacionadas \u00e0 pedofilia. A ordem judicial est\u00e1 sendo executada no Semin\u00e1rio Arquidiocesano, localizado no bairro Castelo Branco, em Jo\u00e3o Pessoa, na tarde desta quarta-feira (06).<\/p>\n<p>A informa\u00e7\u00e3o foi divulgada pelo jornalista Clilson J\u00fanior, durante o programa Arapuan FM, no Sistema Arapuan de Comunica\u00e7\u00e3o. Segundo ele, o seminarista \u00e9 acusado de utilizar um computador pertencente ao Semin\u00e1rio Arquidiocesano para compartilhar imagens de pedofilia pela internet.<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>Reda\u00e7\u00e3o<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" width=\"876\" height=\"585\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2022\/04\/08075628\/arquidiocese_da_pb_walla_santos.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\"><\/p>\n<p>A Justi\u00e7a do Rio Grande do Sul emitiu um mandado de busca e apreens\u00e3o contra um seminarista da\u2026<\/p>\n","protected":false},"author":123457,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[10826,34,66],"tags":[35],"class_list":["post-42647","post","type-post","status-publish","format-standard","hentry","category-destaque-centro-02","category-g1","category-policial","tag-g1"],"author_meta":{"display_name":"Reda\u00e7\u00e3o","author_link":"https:\/\/sindaopcpb.org.br\/author\/redacao\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/destaque-centro-02\/\" class=\"advgb-post-tax-term\">Destaque Centro 02<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/g1\/\" class=\"advgb-post-tax-term\">G1<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">Policial<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Destaque Centro 02<\/span>","<span class=\"advgb-post-tax-term\">G1<\/span>","<span class=\"advgb-post-tax-term\">Policial<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">g1<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">g1<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 2 anos atr\u00e1s","modified":"Atualizado 2 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 6 de dezembro de 2023","modified":"Atualizado em 6 de dezembro de 2023"},"absolute_dates_time":{"created":"Publicado em 6 de dezembro de 2023 13:18","modified":"Atualizado em 6 de dezembro de 2023 15:00"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/42647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/users\/123457"}],"replies":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=42647"}],"version-history":[{"count":3,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/42647\/revisions"}],"predecessor-version":[{"id":42658,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/42647\/revisions\/42658"}],"wp:attachment":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=42647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=42647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=42647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}