{"id":42617,"date":"2023-12-05T16:39:55","date_gmt":"2023-12-05T19:39:55","guid":{"rendered":"https:\/\/www.pbagora.com.br\/?p=794177"},"modified":"2023-12-05T16:39:55","modified_gmt":"2023-12-05T19:39:55","slug":"em-cabedelo-casal-e-preso-e-policia-apreende-drogas-dinheiro-e-armas","status":"publish","type":"post","link":"https:\/\/sindaopcpb.org.br\/index.php\/2023\/12\/05\/em-cabedelo-casal-e-preso-e-policia-apreende-drogas-dinheiro-e-armas\/","title":{"rendered":"Em Cabedelo, casal \u00e9 preso e pol\u00edcia apreende drogas, dinheiro e armas"},"content":{"rendered":"<p><img width=\"380\" height=\"280\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/04\/18074244\/central-de-policia-joao-pessoa-pb-380x280-1.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" style=\"margin-bottom: 20px;\" decoding=\"async\" srcset=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/04\/18074244\/central-de-policia-joao-pessoa-pb-380x280-1.jpg 380w, https:\/\/pbagora.s3.amazonaws.com\/2023\/04\/18074244\/central-de-policia-joao-pessoa-pb-380x280-1-300x221.jpg 300w, https:\/\/pbagora.s3.amazonaws.com\/2023\/04\/18074244\/central-de-policia-joao-pessoa-pb-380x280-1-150x111.jpg 150w, https:\/\/pbagora.s3.amazonaws.com\/2023\/04\/18074244\/central-de-policia-joao-pessoa-pb-380x280-1-80x58.jpg 80w\" sizes=\"(max-width: 380px) 100vw, 380px\" \/><\/p><p>Agentes da Delegacia de Repressa\u0303o ao Crime Organizado (Draco) prenderam, nesta\u00a0 ter\u00e7a-feira (5), um casal suspeito de integrar um grupo que praticava crimes no munic\u00edpio de Cabedelo, na Regi\u00e3o Metropolitana de Jo\u00e3o Pessoa.<\/p>\n<p>Com o homem e a mulher, os policiais apreenderam uma grande quantidade de drogas, armas e dinheiro. Segundo informa\u00e7\u00f5es do delegado Diego Beltr\u00e3o a atividade criminosa na cidade portu\u00e1ria tem atra\u00eddo a aten\u00e7\u00e3o da pol\u00edtica, que segue investigando criminosos ligados a a\u00e7\u00f5es de tr\u00e1fico e at\u00e9 a pr\u00e1tica de homic\u00eddio.<\/p>\n<p>O homem preso nesta ter\u00e7a-feira \u00e9 natural da Bahia e contra ele, ainda segundo a pol\u00edcia, consta um mandato de pris\u00e3o por tr\u00e1fico de drogas. O casal foi conduzido \u00e0 delegacia onde passar\u00e1 por audi\u00eancia de cust\u00f3dia.<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>PB Agora<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"280\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/04\/18074244\/central-de-policia-joao-pessoa-pb-380x280-1.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\"><\/p>\n<p>Agentes da Delegacia de Repressa\u0303o ao Crime Organizado (Draco) prenderam, nesta\u00a0 ter\u00e7a-feira (5), um casal suspeito de integrar\u2026<\/p>\n","protected":false},"author":123457,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[10826,34,66],"tags":[35],"class_list":["post-42617","post","type-post","status-publish","format-standard","hentry","category-destaque-centro-02","category-g1","category-policial","tag-g1"],"author_meta":{"display_name":"Reda\u00e7\u00e3o","author_link":"https:\/\/sindaopcpb.org.br\/author\/redacao\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/destaque-centro-02\/\" class=\"advgb-post-tax-term\">Destaque Centro 02<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/g1\/\" class=\"advgb-post-tax-term\">G1<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">Policial<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Destaque Centro 02<\/span>","<span class=\"advgb-post-tax-term\">G1<\/span>","<span class=\"advgb-post-tax-term\">Policial<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">g1<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">g1<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 2 anos atr\u00e1s","modified":"Atualizado 2 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 5 de dezembro de 2023","modified":"Atualizado em 5 de dezembro de 2023"},"absolute_dates_time":{"created":"Publicado em 5 de dezembro de 2023 16:39","modified":"Atualizado em 5 de dezembro de 2023 16:39"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/42617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/users\/123457"}],"replies":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=42617"}],"version-history":[{"count":3,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/42617\/revisions"}],"predecessor-version":[{"id":42631,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/42617\/revisions\/42631"}],"wp:attachment":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=42617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=42617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=42617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}