{"id":42392,"date":"2023-11-28T16:50:07","date_gmt":"2023-11-28T19:50:07","guid":{"rendered":"https:\/\/www.pbagora.com.br\/?p=792687"},"modified":"2023-11-28T16:50:07","modified_gmt":"2023-11-28T19:50:07","slug":"policia-captura-foragido-da-justica-acusado-de-roubo-na-orla-de-joao-pessoa","status":"publish","type":"post","link":"https:\/\/sindaopcpb.org.br\/index.php\/2023\/11\/28\/policia-captura-foragido-da-justica-acusado-de-roubo-na-orla-de-joao-pessoa\/","title":{"rendered":"Pol\u00edcia captura foragido da Justi\u00e7a acusado de roubo na orla de Jo\u00e3o Pessoa"},"content":{"rendered":"<p><img width=\"1024\" height=\"576\" src=\"https:\/\/pbagora.s3.amazonaws.com\/20191215112130\/ORLA-JP-1024x576.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" style=\"margin-bottom: 20px;\" decoding=\"async\" srcset=\"https:\/\/pbagora.s3.amazonaws.com\/20191215112130\/ORLA-JP-1024x576.jpg 1024w, https:\/\/pbagora.s3.amazonaws.com\/20191215112130\/ORLA-JP-300x169.jpg 300w, https:\/\/pbagora.s3.amazonaws.com\/20191215112130\/ORLA-JP-150x84.jpg 150w, https:\/\/pbagora.s3.amazonaws.com\/20191215112130\/ORLA-JP-768x432.jpg 768w, https:\/\/pbagora.s3.amazonaws.com\/20191215112130\/ORLA-JP-800x450.jpg 800w, https:\/\/pbagora.s3.amazonaws.com\/20191215112130\/ORLA-JP-1160x653.jpg 1160w, https:\/\/pbagora.s3.amazonaws.com\/20191215112130\/ORLA-JP-80x44.jpg 80w, https:\/\/pbagora.s3.amazonaws.com\/20191215112130\/ORLA-JP-600x338.jpg 600w, https:\/\/pbagora.s3.amazonaws.com\/20191215112130\/ORLA-JP.jpg 1365w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p><p>Mais um foragido da Justi\u00e7a acusado do crime de roubo foi preso pela Pol\u00edcia Militar na tarde desta ter\u00e7a-feira (28), em Jo\u00e3o Pessoa. A captura do acusado aconteceu no bairro de Tamba\u00fa.<\/p>\n<p>O homem preso tem 30 anos de idade e foi abordado pelos policiais do Batalh\u00e3o Especializado em Policiamento Tur\u00edstico (BEPTur), durante a\u00e7\u00f5es preventivas de combate ao tr\u00e1fico de drogas na regi\u00e3o do Centro Tur\u00edstico.<\/p>\n<p>De acordo com o comando da unidade, os policiais constataram que contra o homem havia um mandado de pris\u00e3o em aberto expedido pela Vara de Execu\u00e7\u00e3o Penal de Jo\u00e3o Pessoa, pelo crime de roubo.<\/p>\n<p>O acusado preso, que tinha quatro anos de pena em regime fechado para ser cumprida, foi apresentado na delegacia para os procedimentos cab\u00edveis.<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>Ascom PMPB<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/pbagora.s3.amazonaws.com\/20191215112130\/ORLA-JP-1024x576.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\"><\/p>\n<p>Mais um foragido da Justi\u00e7a acusado do crime de roubo foi preso pela Pol\u00edcia Militar na tarde desta\u2026<\/p>\n","protected":false},"author":123457,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[10826,34,66],"tags":[35],"class_list":["post-42392","post","type-post","status-publish","format-standard","hentry","category-destaque-centro-02","category-g1","category-policial","tag-g1"],"author_meta":{"display_name":"Reda\u00e7\u00e3o","author_link":"https:\/\/sindaopcpb.org.br\/author\/redacao\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/destaque-centro-02\/\" class=\"advgb-post-tax-term\">Destaque Centro 02<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/g1\/\" class=\"advgb-post-tax-term\">G1<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">Policial<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Destaque Centro 02<\/span>","<span class=\"advgb-post-tax-term\">G1<\/span>","<span class=\"advgb-post-tax-term\">Policial<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">g1<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">g1<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 2 anos atr\u00e1s","modified":"Atualizado 2 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 28 de novembro de 2023","modified":"Atualizado em 28 de novembro de 2023"},"absolute_dates_time":{"created":"Publicado em 28 de novembro de 2023 16:50","modified":"Atualizado em 28 de novembro de 2023 16:50"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/42392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/users\/123457"}],"replies":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=42392"}],"version-history":[{"count":2,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/42392\/revisions"}],"predecessor-version":[{"id":42402,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/42392\/revisions\/42402"}],"wp:attachment":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=42392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=42392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=42392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}