{"id":42219,"date":"2023-11-23T08:55:19","date_gmt":"2023-11-23T11:55:19","guid":{"rendered":"https:\/\/www.pbagora.com.br\/?p=791352"},"modified":"2023-11-23T11:04:19","modified_gmt":"2023-11-23T14:04:19","slug":"operacao-da-policia-civil-de-goias-mira-mulher-suspeita-de-fraudes-em-aplicativos-bancarios-na-pb","status":"publish","type":"post","link":"https:\/\/sindaopcpb.org.br\/index.php\/2023\/11\/23\/operacao-da-policia-civil-de-goias-mira-mulher-suspeita-de-fraudes-em-aplicativos-bancarios-na-pb\/","title":{"rendered":"Opera\u00e7\u00e3o da Pol\u00edcia Civil de Goi\u00e1s mira mulher suspeita de fraudes em aplicativos banc\u00e1rios na PB"},"content":{"rendered":"<p><img width=\"687\" height=\"463\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/23081227\/csm_mulher_autofraude_23860c5611.jpeg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" decoding=\"async\" loading=\"lazy\" style=\"margin-bottom: 20px;\" srcset=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/23081227\/csm_mulher_autofraude_23860c5611.jpeg 687w, https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/23081227\/csm_mulher_autofraude_23860c5611-300x202.jpeg 300w, https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/23081227\/csm_mulher_autofraude_23860c5611-150x101.jpeg 150w, https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/23081227\/csm_mulher_autofraude_23860c5611-380x256.jpeg 380w, https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/23081227\/csm_mulher_autofraude_23860c5611-80x54.jpeg 80w, https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/23081227\/csm_mulher_autofraude_23860c5611-600x404.jpeg 600w\" sizes=\"(max-width: 687px) 100vw, 687px\" \/><\/p><p>Uma opera\u00e7\u00e3o da Pol\u00edcia Civil de Goi\u00e1s, deflagrada hoje (23), em Jo\u00e3o Pessoa, mirou uma mulher suspeita de fraudes em aplicativos de bancos. A investigada atuava com outras duas pessoas e usava documentos falsos para fazer transfer\u00eancias banc\u00e1rias fraudulentas.<\/p>\n<p>Segundo a investiga\u00e7\u00e3o, os suspeitos abriram contas banc\u00e1rias digitais e desviaram pelo menos R$ 10 mil. A mulher investigada foi localizada no bairro Jardim Veneza. Outros criminosos investigados tamb\u00e9m foram alvos da opera\u00e7\u00e3o que, al\u00e9m da Para\u00edba, ocorreu nos estados de Goi\u00e1s, Paran\u00e1, Rond\u00f4nia e Mato Grosso.<\/p>\n<p>A Pol\u00edcia Civil da Para\u00edba, que participou da a\u00e7\u00e3o, apreendeu materiais que ser\u00e3o analisados e devem complementar a investiga\u00e7\u00e3o.<\/p>\n<p>Reda\u00e7\u00e3o<\/p>\n","protected":false},"excerpt":{"rendered":"<p><img decoding=\"async\" width=\"687\" height=\"463\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/23081227\/csm_mulher_autofraude_23860c5611.jpeg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" loading=\"lazy\"><\/p>\n<p>Uma opera\u00e7\u00e3o da Pol\u00edcia Civil de Goi\u00e1s, deflagrada hoje (23), em Jo\u00e3o Pessoa, mirou uma mulher suspeita de\u2026<\/p>\n","protected":false},"author":123457,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[10823,34,66],"tags":[35],"class_list":["post-42219","post","type-post","status-publish","format-standard","hentry","category-destaque-centro-01","category-g1","category-policial","tag-g1"],"author_meta":{"display_name":"Reda\u00e7\u00e3o","author_link":"https:\/\/sindaopcpb.org.br\/author\/redacao\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/destaque-centro-01\/\" class=\"advgb-post-tax-term\">Destaque Centro 01<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/g1\/\" class=\"advgb-post-tax-term\">G1<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">Policial<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Destaque Centro 01<\/span>","<span class=\"advgb-post-tax-term\">G1<\/span>","<span class=\"advgb-post-tax-term\">Policial<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">g1<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">g1<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 2 anos atr\u00e1s","modified":"Atualizado 2 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 23 de novembro de 2023","modified":"Atualizado em 23 de novembro de 2023"},"absolute_dates_time":{"created":"Publicado em 23 de novembro de 2023 08:55","modified":"Atualizado em 23 de novembro de 2023 11:04"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/42219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/users\/123457"}],"replies":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=42219"}],"version-history":[{"count":2,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/42219\/revisions"}],"predecessor-version":[{"id":42224,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/42219\/revisions\/42224"}],"wp:attachment":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=42219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=42219"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=42219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}