{"id":42166,"date":"2023-11-21T16:10:34","date_gmt":"2023-11-21T19:10:34","guid":{"rendered":"https:\/\/www.pbagora.com.br\/?p=790914"},"modified":"2023-11-21T19:40:34","modified_gmt":"2023-11-21T22:40:34","slug":"advogado-de-defesa-do-padre-egidio-sheyner-asfora-deixa-o-caso-confira-nota","status":"publish","type":"post","link":"https:\/\/sindaopcpb.org.br\/index.php\/2023\/11\/21\/advogado-de-defesa-do-padre-egidio-sheyner-asfora-deixa-o-caso-confira-nota\/","title":{"rendered":"Advogado de defesa do Padre Eg\u00eddio, Sheyner Asfora deixa o caso; confira nota"},"content":{"rendered":"<p><img width=\"1024\" height=\"576\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/21161206\/Advogado-Sheyner-Asfora-e-Padre-Egidio-1024x576.jpeg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" decoding=\"async\" loading=\"lazy\" style=\"margin-bottom: 20px;\" srcset=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/21161206\/Advogado-Sheyner-Asfora-e-Padre-Egidio-1024x576.jpeg 1024w, https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/21161206\/Advogado-Sheyner-Asfora-e-Padre-Egidio-300x169.jpeg 300w, https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/21161206\/Advogado-Sheyner-Asfora-e-Padre-Egidio-150x84.jpeg 150w, https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/21161206\/Advogado-Sheyner-Asfora-e-Padre-Egidio-768x432.jpeg 768w, https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/21161206\/Advogado-Sheyner-Asfora-e-Padre-Egidio-380x214.jpeg 380w, https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/21161206\/Advogado-Sheyner-Asfora-e-Padre-Egidio-800x450.jpeg 800w, https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/21161206\/Advogado-Sheyner-Asfora-e-Padre-Egidio-1160x652.jpeg 1160w, https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/21161206\/Advogado-Sheyner-Asfora-e-Padre-Egidio-80x46.jpeg 80w, https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/21161206\/Advogado-Sheyner-Asfora-e-Padre-Egidio-760x427.jpeg 760w, https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/21161206\/Advogado-Sheyner-Asfora-e-Padre-Egidio-600x337.jpeg 600w, https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/21161206\/Advogado-Sheyner-Asfora-e-Padre-Egidio.jpeg 1366w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p><p>Em comunicado \u00e0 imprensa divulgado na tarde desta ter\u00e7a-feira (21), o advogado Sheyner Asf\u00f3ra deixou a defesa do Padre Eg\u00eddio, suspeito de liderar um suposto esquema de desvio de dinheiro do Hospital Padre Z\u00e9, em Jo\u00e3o Pessoa.<\/p>\n<p>Asf\u00f3ra disse que renunciou &#8220;os poderes que me foram outorgados por raz\u00f5es de incompatibilidade de estilo com rela\u00e7\u00e3o a atua\u00e7\u00e3o adotada pelos colegas advogados que continuar\u00e3o no patroc\u00ednio dos interesses do at\u00e9 ent\u00e3o constituinte&#8221;.<\/p>\n<p>O Padre Eg\u00eddio foi preso na \u00faltima sexta-feira (17). Ele \u00e9 acusado de usar a verba do Hospital para adquirir im\u00f3veis de luxo, vinhos, carros, entre outros. Duas ex-diretoras do Padre Z\u00e9 tamb\u00e9m foram presas.<\/p>\n<p><strong>Confira a nota:<\/strong><\/p>\n<p>COMUNICADO \u00c0 IMPRENSA<\/p>\n<p><em>Informo \u00e0 imprensa que n\u00e3o mais patrocino a defesa do padre Eg\u00eddio de Carvalho Neto, uma vez que renunciei os poderes que me foram outorgados por raz\u00f5es de incompatibilidade de estilo com rela\u00e7\u00e3o a atua\u00e7\u00e3o adotada pelos colegas advogados que continuar\u00e3o no patroc\u00ednio dos interesses do at\u00e9 ent\u00e3o constituinte.<\/em><\/p>\n<p><em>Assim, por quest\u00e3o de justi\u00e7a e reconhecimento, registro, nesta oportunidade, o meu agradecimento ao padre Eg\u00eddio pela confian\u00e7a depositada em meu trabalho profissional que exerci com \u00e9tica, boa t\u00e9cnica, zelo e dedica\u00e7\u00e3o, atributos esses que tenho honra e orgulho de serem os condutores da minha trajet\u00f3ria de mais de 20 anos de exerc\u00edcio da advocacia criminal.<\/em><\/p>\n<p><em>Esclare\u00e7o, ainda, que exerci o meu dever de comunica\u00e7\u00e3o desta minha decis\u00e3o pessoalmente ao padre Eg\u00eddio de Carvalho Neto e, por conseguinte, protocolei a peti\u00e7\u00e3o de ren\u00fancia nos autos do processo que tramita perante o Poder Judici\u00e1rio paraibano.<\/em><\/p>\n<p><em>Dessa forma, em estrita observ\u00e2ncia ao C\u00f3digo de \u00c9tica e Disciplina da OAB, declaro que n\u00e3o mais irei me pronunciar sobre o presente caso objeto deste comunicado de ren\u00fancia.<\/em><\/p>\n<p><em>Jo\u00e3o Pessoa\/PB, 21 de novembro de 2023<\/em><\/p>\n<p><em>SHEYNER ASF\u00d3RA<\/em><\/p>\n<p><em>OAB\/PB 11.590<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>PB Agora<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/21161206\/Advogado-Sheyner-Asfora-e-Padre-Egidio-1024x576.jpeg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" loading=\"lazy\"><\/p>\n<p>Em comunicado \u00e0 imprensa divulgado na tarde desta ter\u00e7a-feira (21), o advogado Sheyner Asf\u00f3ra deixou a defesa do\u2026<\/p>\n","protected":false},"author":123457,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[34,66],"tags":[35],"class_list":["post-42166","post","type-post","status-publish","format-standard","hentry","category-g1","category-policial","tag-g1"],"author_meta":{"display_name":"Reda\u00e7\u00e3o","author_link":"https:\/\/sindaopcpb.org.br\/author\/redacao\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/g1\/\" class=\"advgb-post-tax-term\">G1<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">Policial<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">G1<\/span>","<span class=\"advgb-post-tax-term\">Policial<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">g1<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">g1<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 2 anos atr\u00e1s","modified":"Atualizado 2 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 21 de novembro de 2023","modified":"Atualizado em 21 de novembro de 2023"},"absolute_dates_time":{"created":"Publicado em 21 de novembro de 2023 16:10","modified":"Atualizado em 21 de novembro de 2023 19:40"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/42166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/users\/123457"}],"replies":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=42166"}],"version-history":[{"count":3,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/42166\/revisions"}],"predecessor-version":[{"id":42174,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/42166\/revisions\/42174"}],"wp:attachment":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=42166"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=42166"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=42166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}