{"id":42006,"date":"2023-11-18T07:40:24","date_gmt":"2023-11-18T10:40:24","guid":{"rendered":"https:\/\/www.pbagora.com.br\/?p=790109"},"modified":"2023-11-18T14:21:24","modified_gmt":"2023-11-18T17:21:24","slug":"policia-prende-homem-suspeito-de-atirar-em-ex-esposa-ex-cunhado-e-sequestrar-filha-em-campina-grande","status":"publish","type":"post","link":"https:\/\/sindaopcpb.org.br\/index.php\/2023\/11\/18\/policia-prende-homem-suspeito-de-atirar-em-ex-esposa-ex-cunhado-e-sequestrar-filha-em-campina-grande\/","title":{"rendered":"Pol\u00edcia prende homem suspeito de atirar em ex-esposa; ex-cunhado, e \u201csequestrar\u201d filha em Campina Grande"},"content":{"rendered":"<p><img width=\"984\" height=\"554\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/18074004\/prisssss.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"\" decoding=\"async\" loading=\"lazy\" style=\"margin-bottom: 20px;\" srcset=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/18074004\/prisssss.webp 984w, https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/18074004\/prisssss-300x169.webp 300w, https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/18074004\/prisssss-150x84.webp 150w, https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/18074004\/prisssss-768x432.webp 768w, https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/18074004\/prisssss-380x214.webp 380w, https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/18074004\/prisssss-800x450.webp 800w, https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/18074004\/prisssss-80x46.webp 80w, https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/18074004\/prisssss-760x428.webp 760w, https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/18074004\/prisssss-600x338.webp 600w\" sizes=\"(max-width: 984px) 100vw, 984px\" \/><\/p><p>A Pol\u00edcia Civil prendeu o homem suspeito de tentar matar a ex-esposa; balear o ex-cunhado e depois fugir com a filha de cinco anos em Campina Grande. O caso aconteceu na noite de quarta-feira (15), no bairro da Catingueira, na zona sul de Campina Grande, Agreste da Para\u00edba. A pris\u00e3o foi ontem \u00e0 tarde. A filha do casal foi encaminhada para a casa de uma av\u00f3, logo ap\u00f3s a pris\u00e3o do homem.<\/p>\n<p>Segundo a Pol\u00edcia Civil, o homem se entregou na Central de Pol\u00edcia e juntamente com o advogado, com a filha de cinco anos que havia sido sequestrada pelo pai. Ele tamb\u00e9m entregou a arma usada no crime. A crian\u00e7a foi encaminhada para a casa da av\u00f3.<\/p>\n<p>A pris\u00e3o preventiva do homem foi decretada e ele foi levado ao Numol de Campina Grande para realizar exame de corpo delito. Ap\u00f3s realizar exames no Numol, ele ser\u00e1 encaminhado para a carceragem da Central de Pol\u00edcia de Campina Grande e, no s\u00e1bado (18), passar\u00e1 por audi\u00eancia de cust\u00f3dia.<\/p>\n<p>A mulher que foi baleada pelo homem, que est\u00e1 gr\u00e1vida de quatro meses, segue internada na enfermaria do Hospital de Emerg\u00eancia e Trauma de Campina Grande e, segundo a assessoria da unidade hospitalar, o quadro cl\u00ednico dela \u00e9 est\u00e1vel. Ainda segundo o hospital, o beb\u00ea est\u00e1 bem.<\/p>\n<p>De acordo com a Pol\u00edcia Civil, o vigilante, que trabalhava em um clube de tiro em Campina Grande, estava de folga e pediu para trocar a folga com um colega de trabalho e trabalhar no dia, para ter acesso \u00e0 arma da empresa, na noite de quarta-feira, 15 de novembro, no bairro da Catingueira, na zona sul de Campina Grande, Agreste da Para\u00edba.<\/p>\n<p>Em casa, ele\u00a0 teria pego a arma e se dirigiu at\u00e9 a casa da ex-companheira, que fica no bairro da Catingueira. Chegando no local, inconformado com o t\u00e9rmino do relacionamento do casal, que estava em processo de separa\u00e7\u00e3o, o vigilante teria disparado contra a mulher. Um cunhado que chegou no local para intervir tamb\u00e9m foi atingido por um disparo.<\/p>\n<p><strong><em>Reda\u00e7\u00e3o<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" width=\"984\" height=\"554\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/18074004\/prisssss.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"\"><\/p>\n<p>A Pol\u00edcia Civil prendeu o homem suspeito de tentar matar a ex-esposa; balear o ex-cunhado e depois fugir\u2026<\/p>\n","protected":false},"author":123457,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[34,66,10827],"tags":[35],"class_list":["post-42006","post","type-post","status-publish","format-standard","hentry","category-g1","category-policial","category-rodape-02","tag-g1"],"author_meta":{"display_name":"Reda\u00e7\u00e3o","author_link":"https:\/\/sindaopcpb.org.br\/author\/redacao\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/g1\/\" class=\"advgb-post-tax-term\">G1<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">Policial<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/rodape-02\/\" class=\"advgb-post-tax-term\">Rodape 02<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">G1<\/span>","<span class=\"advgb-post-tax-term\">Policial<\/span>","<span class=\"advgb-post-tax-term\">Rodape 02<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/rodape-02\/\" class=\"advgb-post-tax-term\">g1<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">g1<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 2 anos atr\u00e1s","modified":"Atualizado 2 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 18 de novembro de 2023","modified":"Atualizado em 18 de novembro de 2023"},"absolute_dates_time":{"created":"Publicado em 18 de novembro de 2023 07:40","modified":"Atualizado em 18 de novembro de 2023 14:21"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/42006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/users\/123457"}],"replies":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=42006"}],"version-history":[{"count":3,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/42006\/revisions"}],"predecessor-version":[{"id":42020,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/42006\/revisions\/42020"}],"wp:attachment":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=42006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=42006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=42006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}