{"id":41741,"date":"2023-11-12T13:25:26","date_gmt":"2023-11-12T16:25:26","guid":{"rendered":"https:\/\/www.pbagora.com.br\/?p=788817"},"modified":"2023-11-12T17:45:26","modified_gmt":"2023-11-12T20:45:26","slug":"homem-e-assassinado-e-mulher-morrer-vitima-de-bala-perdida-em-princesa-isabel-no-sertao-da-paraiba","status":"publish","type":"post","link":"https:\/\/sindaopcpb.org.br\/index.php\/2023\/11\/12\/homem-e-assassinado-e-mulher-morrer-vitima-de-bala-perdida-em-princesa-isabel-no-sertao-da-paraiba\/","title":{"rendered":"Homem e mulher mortos a tiros em Princesa Isabel eram integrantes do MST; Movimento pede justi\u00e7a"},"content":{"rendered":"<p><img width=\"571\" height=\"415\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/12162630\/vitimas-MST.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" decoding=\"async\" loading=\"lazy\" style=\"margin-bottom: 20px;\" srcset=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/12162630\/vitimas-MST.jpg 571w, https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/12162630\/vitimas-MST-300x218.jpg 300w, https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/12162630\/vitimas-MST-150x109.jpg 150w, https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/12162630\/vitimas-MST-380x276.jpg 380w, https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/12162630\/vitimas-MST-80x58.jpg 80w\" sizes=\"(max-width: 571px) 100vw, 571px\" \/><\/p><p>Na noite desse s\u00e1bado (11), um homem e uma mulher, trabalhadores do Movimento dos Trabalhadores e Trabalhadoras Rurais Sem Terra da Para\u00edba (MST), foram mortos v\u00edtimas de disparos de arma de fogo.<\/p>\n<p>O crime ocorreu no S\u00edtio Rancho Dantas, na Zona Rural do munic\u00edpio de Princesa Isabel, no Sert\u00e3o da Para\u00edba, e, de acordo com informa\u00e7\u00f5es da pol\u00edcia, o homem, identificado como Aldeci, 44 anos, estava fazendo um servi\u00e7o em cima de uma casa no S\u00edtio Lage quando os suspeitos chegaram.<\/p>\n<p>A dupla, fazendo uso de capuz, se aproximou da resid\u00eancia em uma moto vermelha e mandou que Aldeci descesse para assinar um papel. Aos policiais foi dito que antes mesmo da v\u00edtima descer a escada passou a ser alvo dos disparos efetuados pelos desconhecidos.<\/p>\n<p>Ana Paula, de 29 anos, que segurava a escada no momento do crime, foi atingida na cabe\u00e7a por um dos disparos.<\/p>\n<p>Devido a gravidade dos ferimentos, Aldeci morreu antes mesmo da chegada do socorro. J\u00e1 Ana Paula, chegou a ser socorrida para a Unidade de Pronto Atendimento (UPA), mas tamb\u00e9m n\u00e3o resistiu e faleceu ap\u00f3s dar entrada no hospital.<\/p>\n<p>Ainda n\u00e3o h\u00e1 informa\u00e7\u00f5es sobre a autoria e a motiva\u00e7\u00e3o do crime.<\/p>\n<p>Em publica\u00e7\u00e3o nas redes sociais, o MST da Para\u00edba denunciou o crime e exigiu justi\u00e7a pelas mortes. \u201cO MST cobra a apura\u00e7\u00e3o do crime e a pris\u00e3o dos autores. Enquanto movimento, reafirmamos nossa luta contra toda forma de viol\u00eancia. Aos nossos mortos nenhum segundo de sil\u00eancio, mas uma vida toda de luta\u201d, afirmam em nota.<\/p>\n<p>Coordenador do acampamento, Aldecy Viturino tinha 2 filhos. Ana Paula tinha 3 filhos.<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>PB Agora<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" width=\"571\" height=\"415\" src=\"https:\/\/pbagora.s3.amazonaws.com\/2023\/11\/12162630\/vitimas-MST.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\"><\/p>\n<p>Na noite desse s\u00e1bado (11), um homem e uma mulher, trabalhadores do Movimento dos Trabalhadores e Trabalhadoras Rurais\u2026<\/p>\n","protected":false},"author":123457,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[34,66,10824],"tags":[35],"class_list":["post-41741","post","type-post","status-publish","format-standard","hentry","category-g1","category-policial","category-principal3","tag-g1"],"author_meta":{"display_name":"Reda\u00e7\u00e3o","author_link":"https:\/\/sindaopcpb.org.br\/author\/redacao\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/g1\/\" class=\"advgb-post-tax-term\">G1<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/policial\/\" class=\"advgb-post-tax-term\">Policial<\/a>","<a href=\"https:\/\/sindaopcpb.org.br\/principal3\/\" class=\"advgb-post-tax-term\">Principal3<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">G1<\/span>","<span class=\"advgb-post-tax-term\">Policial<\/span>","<span class=\"advgb-post-tax-term\">Principal3<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/principal3\/\" class=\"advgb-post-tax-term\">g1<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">g1<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 2 anos atr\u00e1s","modified":"Atualizado 2 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 12 de novembro de 2023","modified":"Atualizado em 12 de novembro de 2023"},"absolute_dates_time":{"created":"Publicado em 12 de novembro de 2023 13:25","modified":"Atualizado em 12 de novembro de 2023 17:45"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/41741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/users\/123457"}],"replies":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=41741"}],"version-history":[{"count":6,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/41741\/revisions"}],"predecessor-version":[{"id":41755,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/41741\/revisions\/41755"}],"wp:attachment":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=41741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=41741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=41741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}