{"id":31519,"date":"2023-08-26T14:13:36","date_gmt":"2023-08-26T17:13:36","guid":{"rendered":"https:\/\/g1.globo.com\/pb\/paraiba\/noticia\/2023\/08\/26\/stj-manda-soltar-prefeito-de-sao-mamede-pb-preso-em-operacao-da-pf.ghtml"},"modified":"2023-08-26T14:13:36","modified_gmt":"2023-08-26T17:13:36","slug":"stj-manda-soltar-prefeito-de-sao-mamede-pb-preso-em-operacao-da-pf","status":"publish","type":"post","link":"https:\/\/sindaopcpb.org.br\/index.php\/2023\/08\/26\/stj-manda-soltar-prefeito-de-sao-mamede-pb-preso-em-operacao-da-pf\/","title":{"rendered":"STJ manda soltar prefeito de S\u00e3o Mamede, PB, preso em opera\u00e7\u00e3o da PF"},"content":{"rendered":"   <img src=\"https:\/\/s2.glbimg.com\/03CdgQhZg-sry3YEvteyPSRtbbE=\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2023\/v\/N\/EOkmJ8SZKSBRyD2C1AtA\/prefeito-de-sao-mamede.jpeg\" \/><br \/>     Umberto Jefferson (Uni\u00e3o Brasil) \u00e9 investigado por direcionamento de licita\u00e7\u00f5es, desvio de recursos e lavagem de dinheiro. Ele foi preso no dia 15 de agosto. Prefeito de S\u00e3o Mamede, Umberto Jefferson\nDivulga\u00e7\u00e3o\nUma decis\u00e3o do Superior Tribunal de Justi\u00e7a (STJ), neste s\u00e1bado (26), mandou soltar o prefeito de S\u00e3o Mamede, Sert\u00e3o da Para\u00edba, Umberto Jefferson (Uni\u00e3o Brasil). O prefeito foi alvo de opera\u00e7\u00e3o \"Festa no Terreiro 2\" da Pol\u00edcia Federal, e al\u00e9m de preso foi afastado do cargo.\nA liminar determinando a soltura de Umberto foi uma decis\u00e3o do ministro Jo\u00e3o Batista Moreira, em um pedido de habeas corpus.\nA segunda fase da opera\u00e7\u00e3o \"Festa no Terreiro\", foi realizada no dia 15 de agosto. A a\u00e7\u00e3o foi feita para  combater o direcionamento de licita\u00e7\u00f5es, desvios de recursos p\u00fablicos, corrup\u00e7\u00e3o e lavagem de dinheiro no munic\u00edpio.\nSegundo a PF, al\u00e9m de Umberto Jefferson , tamb\u00e9m foram presos Maxwell Brian, Josivan Marques e Eumar Carvalho Maia e Jo\u00e3o Lopes Neto, que se entregou em um segundo momento. \nEntre os casos de fraude investigados, est\u00e1 a a\u00e7\u00e3o do prefeito, junto com Jo\u00e3o Lopes,  em um aditivo de um processo licitat\u00f3rio, no qual o valor inicial estava fixado em R$ 8,35 milh\u00f5es e, subiu, posteriormente, para R$ 10,10 milh\u00f5es, nove meses ap\u00f3s a assinatura do contrato. A PF julga este movimento como \u2018t\u00edpico de atividades sistem\u00e1ticas de desvio de verbas p\u00fablicas\u2019. \nAinda nas investiga\u00e7\u00f5es, a pol\u00edcia apurou que a constru\u00e7\u00e3o de uma mans\u00e3o, em um condom\u00ednio de luxo em Patos, tamb\u00e9m no Sert\u00e3o, e de propriedade do prefeito, teria sido constru\u00edda com verbas desviadas do munic\u00edpio. \nOpera\u00e7\u00e3o Festa no Terreiro 2\nOpera\u00e7\u00e3o Festa no Terreiro 2 apura suspeita de fraudes em licita\u00e7\u00e3o pelo prefeito de S\u00e3o Mamede, na PB\nDivulga\u00e7\u00e3o\/Pol\u00edcia Federal\nA opera\u00e7\u00e3o, batizada de \u201cFesta no Terreiro 2\u201d, \u00e9 a continua\u00e7\u00e3o da investiga\u00e7\u00e3o que culminou com a primeira fase da opera\u00e7\u00e3o, em 2 de mar\u00e7o deste ano, e que apura preju\u00edzos de cerca de R$ 8 milh\u00f5es aos cofres p\u00fablicos. Por sua vez, a pr\u00f3pria opera\u00e7\u00e3o Festa no Terreiro j\u00e1 \u00e9 um desdobramento da opera\u00e7\u00e3o Bleeder, cuja primeira fase aconteceu em 2021, e a fase mais recente foi no dia 9 de mar\u00e7o. O nome da opera\u00e7\u00e3o \u00e9 uma refer\u00eancia ao termo usado pelos investigados ao combinar o resultado de licita\u00e7\u00f5es.\nV\u00eddeos mais assistidos do g1 Para\u00edba  ","protected":false},"excerpt":{"rendered":"<p>        Umberto Jefferson (Uni\u00e3o Brasil) \u00e9 investigado por direcionamento de licita\u00e7\u00f5es, desvio de recursos e lavagem de dinheiro. Ele foi preso no dia 15 de agosto. Prefeito de S\u00e3o Mamede, Umberto Jefferson<br \/>\nDivulga\u00e7\u00e3o<br \/>\nUma decis\u00e3o do Superior Tribunal &#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[34],"tags":[35],"class_list":["post-31519","post","type-post","status-publish","format-standard","hentry","category-g1","tag-g1"],"author_meta":{"display_name":"g1 &gt; Para\u00edba","author_link":"https:\/\/sindaopcpb.org.br\/author\/g1-paraiba\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/g1\/\" class=\"advgb-post-tax-term\">G1<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">G1<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/sindaopcpb.org.br\/g1\/\" class=\"advgb-post-tax-term\">g1<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">g1<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 3 anos atr\u00e1s","modified":"Atualizado 3 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 26 de agosto de 2023","modified":"Atualizado em 26 de agosto de 2023"},"absolute_dates_time":{"created":"Publicado em 26 de agosto de 2023 14:13","modified":"Atualizado em 26 de agosto de 2023 14:13"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/31519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=31519"}],"version-history":[{"count":2,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/31519\/revisions"}],"predecessor-version":[{"id":31612,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/posts\/31519\/revisions\/31612"}],"wp:attachment":[{"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=31519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=31519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindaopcpb.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=31519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}